{"id":10000032,"date":"2020-11-27T13:55:31","date_gmt":"2020-11-27T12:55:31","guid":{"rendered":"https:\/\/www.fh-joanneum.at\/akademische-peer-beraterin-akademischer-peer-berater\/academic_certificate_programme\/?page_id=32"},"modified":"2020-11-27T13:56:16","modified_gmt":"2020-11-27T12:56:16","slug":"studienplan","status":"publish","type":"page","link":"https:\/\/www.fh-joanneum.at\/akademische-peer-beraterin-akademischer-peer-berater\/academic_certificate_programme\/im-lehrgang\/studienplan\/","title":{"rendered":"Studienplan"},"content":{"rendered":"<div\n    id=\"\"\n    class=\"wp-block-curriculum margin-bottom-normal\"\n>\n    <div class=\"container-lg\">\n        <div class=\"row\">\n                            <div class=\"col-12\">\n                    <h2>Aktueller Studienplan<\/h2>\n                <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-1630090342\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>1. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-1630090342\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-einzelselbsterfahrung-i-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-einzelselbsterfahrung-i\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Person als Werkzeug |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_101<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Einzelselbsterfahrung I<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">0.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-einzelselbsterfahrung-i\"\n                                                        aria-labelledby=\"course-einzelselbsterfahrung-i-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Einzelselbsterfahrung: Eigene Rolle, Biografie, Sozialisation, \u00c4ngste, St\u00e4rken, Schw\u00e4chen erkennen.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-gruppenselbsterfahrung-i-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-gruppenselbsterfahrung-i\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Person als Werkzeug |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_108<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Gruppenselbsterfahrung I<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-gruppenselbsterfahrung-i\"\n                                                        aria-labelledby=\"course-gruppenselbsterfahrung-i-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Gruppenselbsterfahrung: Rolle in der Gruppe, Problemstellungen in Gruppen, Reflexion der eigenen Leistung in Gruppen, Zufriedenheit in Gruppen, Leitung von Gruppen.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-dienstleistungsangebote-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-dienstleistungsangebote\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Praxis der Peer-Beratung |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2090024_106<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Dienstleistungsangebote<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-dienstleistungsangebote\"\n                                                        aria-labelledby=\"course-dienstleistungsangebote-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        \n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-biografie-und-lebenswelten-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-biografie-und-lebenswelten\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Theorie der Peer-Beratung |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_107<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Biografie und Lebenswelten<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-biografie-und-lebenswelten\"\n                                                        aria-labelledby=\"course-biografie-und-lebenswelten-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Reflexionstechniken (eigenes Erfahrungswissen); Biografiearbeit; Individuelle Entwicklung \u00fcber die Lebensspanne, Beeinflussung durch Bildungsprozesse, individuelle Lern- und Entwicklungspotential im Rahmen gesellschaftlich-kulturellen Bedingungen [THIERSCH, H.: Lebensweltorientierte Soziale Beratung (2007); RAUCHFEISCH, U.: Menschen in psychosozialer Not. Beratung, Betreuung, Psychotherapie (1996)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-einfuhrung-konzept-peer-beratung-peer-counseling-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-einfuhrung-konzept-peer-beratung-peer-counseling\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Theorie der Peer-Beratung |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_102<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Einf\u00fchrung Konzept Peer-Beratung (Peer Counseling)<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-einfuhrung-konzept-peer-beratung-peer-counseling\"\n                                                        aria-labelledby=\"course-einfuhrung-konzept-peer-beratung-peer-counseling-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Einf\u00fchrung, Grundbegriffe und Darstellungsformen; Struktur und Entwurf Selbstbestimmung. Abgrenzung zur Fremdbestimmung; Auswirkungen auf das Selbstverst\u00e4ndnis von Menschen mit Beeintr\u00e4chtigungen. Geschichte und Philosophie der Selbstbestimmt-Leben-Bewegung (international und national). [MILES-PAUL, O.: Wir sind nicht mehr aufzuhalten, Behinderte auf dem Weg zur Selbstbestimmung (1992)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-grundlagen-der-beratung-i-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-grundlagen-der-beratung-i\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Theorie der Peer-Beratung |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_105<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Grundlagen der Beratung I<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-grundlagen-der-beratung-i\"\n                                                        aria-labelledby=\"course-grundlagen-der-beratung-i-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Reflexionstechniken (allgemein), Beratungskonzepte und Methoden. Einzel-, Paar-, Gruppenberatungen. Peer-Counseling  (Prinzipien, Rahmenbedingungen). \u00dcbungen. [BELARDI, N. u.a.: Beratung.Eine sozialp\u00e4dagogische Einf\u00fchrung (2005); HERRIGER, N.: Empowerment in der Sozialen Arbeit (2002); NESTMANN, F. u.a.: Handbuch der Beratung (2007); SCHLIPPE, A.v. u.J. SCHWEITZER: Lehrbuch der systemischen Therapie und Beratung (2012); RAUCHFEISCH, U.: Menschen in psychosozialer Not, Beratung, Beteruung, Psychotherapie (1996); von Bebenburg, Manfred: Wege aus einem Labyrinth \u2013 oder: wie Beratung gelingen kann (2005)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-handlungsfelder-menschen-mit-behinderungen-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-handlungsfelder-menschen-mit-behinderungen\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Theorie der Peer-Beratung |\n                                                            Vorlesung\n                                                            (VO)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_103<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Handlungsfelder Menschen mit Behinderung(en)<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-handlungsfelder-menschen-mit-behinderungen\"\n                                                        aria-labelledby=\"course-handlungsfelder-menschen-mit-behinderungen-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Behinderungen\/Psychiatrieerfahrungen\/Lernschwierigkeiten: Formen, Ursachen von Behinderungen, Umgang mit Unsicherheit und psychischen Barrieren in der Arbeit mit KlientInnen. Lebensbereiche: Geburt, Kindheit, Jugend, Schule, Ausbildung, Berufst\u00e4tigkeit\/Karriere, Inklusion. Euthanasie in der NS-Zeit. Pr\u00e4nataldiagnostik und ethische Fragen. Definition von Behinderung &#8211; vom medizinischen zum sozialen Modell [HALBRAINER, H., VENNEMANN, U. (Hg.): Es war nicht immer so, Zwischen Vernichtung und Selbstbestimmung 1938 bis heute (2014); PRETTENTHALER-ZIEGERHOFER, A. (Hg): Menschen mit Behinderung-Leben wie andere auch? (2006); SAAL, F.: Warum sollte ich jemand anderes sein wollen? Erfahrungen eines Behinderten (2011)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-kommunikation-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-kommunikation\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Theorie der Peer-Beratung |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_104<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Kommunikation<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-kommunikation\"\n                                                        aria-labelledby=\"course-kommunikation-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kommunikationsanalyse; Entwickeln von Haltungen und Strategien in Gespr\u00e4chen mit Einzelpersonen oder vor Publikum. Entwicklungskompetenz von Argumentationen und Pr\u00e4sentationskompetenz von Eigen- und Fremdstandpunkten. [WATZLAWIK, P. u.a.: Menschliche Kommunikation (1969); SCHULZ VON THUN, F.: Miteinander reden \u2013 St\u00f6rungen und Kl\u00e4rungen, Allgemeine Psychologie der Kommunikation (1981);  AMBERGER, S. u.a.: Fit vor Kamera und Mikrofon (2001); ROSENBERG, M.B.: Gewaltfreie Kommunikation, 4.Aufl. (2003)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-lern-und-arbeitstechniken-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-lern-und-arbeitstechniken\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Theorie der Peer-Beratung |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_109<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Lern- und Arbeitstechniken<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-lern-und-arbeitstechniken\"\n                                                        aria-labelledby=\"course-lern-und-arbeitstechniken-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Literaturrecherche, Nutzung von Datenbanken und virtuellen Portalen, Inhalte aufnehmen und wiedergeben, Lernen lernen,  Einsatz von Hilfsmitteln (Leichter Lesen Versionen, Braille, Geb\u00e4rdensprache, Unterst\u00fctzte Kommunikation), [BASTIAN, J., L. GRO\u00df: Lerntechniken und Wissensmanagement (2012); ECO, U.: Wie man eine wissenschaftliche Abschlu\u00dfarbeit schreibt (2010); WILKEN, E. (Hg.): Unterst\u00fctzte Kommunikation, Eine Einf\u00fchrung in Theorie und Praxis (2014)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-1336553607\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>2. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-1336553607\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-einzelselbsterfahrung-ii-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-einzelselbsterfahrung-ii\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Person als Werkzeug |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_202<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Einzelselbsterfahrung II<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">0.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-einzelselbsterfahrung-ii\"\n                                                        aria-labelledby=\"course-einzelselbsterfahrung-ii-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Einzelselbsterfahrung: Eigene Rolle, Biografie, Sozialisation, \u00c4ngste, St\u00e4rken, Schw\u00e4chen erkennen.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-gruppenselbsterfahrung-ii-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-gruppenselbsterfahrung-ii\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Person als Werkzeug |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_203<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Gruppenselbsterfahrung II<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-gruppenselbsterfahrung-ii\"\n                                                        aria-labelledby=\"course-gruppenselbsterfahrung-ii-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Gruppenselbsterfahrung: Rolle in der Gruppe, Problemstellungen in Gruppen, Reflexion der eigenen Leistung in Gruppen, Zufriedenheit in Gruppen, Leitung von Gruppen.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-praktikumsvorbereitung-beratung-begleitung-betreuung-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-praktikumsvorbereitung-beratung-begleitung-betreuung\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Person als Werkzeug |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_204<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Praktikumsvorbereitung (Beratung, Begleitung, Betreuung)<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.50<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-praktikumsvorbereitung-beratung-begleitung-betreuung\"\n                                                        aria-labelledby=\"course-praktikumsvorbereitung-beratung-begleitung-betreuung-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Was bedeutet Beratung, Begleitung, Betreuung? \u00dcbung von Dokumentation, Gespr\u00e4chsf\u00fchrung. Problemstellungen beim Erstgespr\u00e4ch, L\u00f6sung von Zuweisungsproblemen, Erstellung von Hilfepl\u00e4nen, Besprechung von Good-Practise F\u00e4llen, Problembesprechung.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-grundlagen-der-beratung-ii-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-grundlagen-der-beratung-ii\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Praxis der Peer-Beratung |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_201<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Grundlagen der Beratung II<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-grundlagen-der-beratung-ii\"\n                                                        aria-labelledby=\"course-grundlagen-der-beratung-ii-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        \u00dcberblick \u00fcber die Beratungsformate Coaching, Supervision,  Konfliktregelungen \/Verstehen\/Fragen\/Kommentieren\/Reformulieren\/Intervenieren\/Selbst-Evaluieren [SCHWARZ, G.: Konfliktmanagement, Sechs Grundmodelle der Konfliktl\u00f6sung, 3.Aufl. (1997); RAUEN, C., u.a.: Handbuch Coaching (2005); K\u00dcHL, S.: Coaching und Supervision, Zur personenorientierten Beratung in Organisationen (2008)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-intersektionalitat-im-bereiche-behinderungen-von-einander-lernen-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-intersektionalitat-im-bereiche-behinderungen-von-einander-lernen\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Praxis der Peer-Beratung |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_205<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Intersektionalit\u00e4t im Bereiche Behinderung(en) (Von einander lernen)<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-intersektionalitat-im-bereiche-behinderungen-von-einander-lernen\"\n                                                        aria-labelledby=\"course-intersektionalitat-im-bereiche-behinderungen-von-einander-lernen-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Wohnen, Pers\u00f6nliche Assistenz,  Sexualit\u00e4t, Beziehung, Reisen\/Mobilit\u00e4t, Trauerarbeit, Freizeit, Alter, Selbst\/Fremdbestimmung.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-soziales-psychisches-und-korperliches-wohlbefinden-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-soziales-psychisches-und-korperliches-wohlbefinden\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Praxis der Peer-Beratung |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_206<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Soziales, psychisches und k\u00f6rperliches Wohlbefinden<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-soziales-psychisches-und-korperliches-wohlbefinden\"\n                                                        aria-labelledby=\"course-soziales-psychisches-und-korperliches-wohlbefinden-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Gesunde Lebensf\u00fchrung (Ern\u00e4hrung, Bewegung, Sport &#038; Fitness), soziale Ausgewogenheit, Stress &#038; Druck, soziale Beziehungen, Gl\u00fcck &#038; Humor. Fokus: Menschen mit k\u00f6rperl. Behinderung(en) oder Menschen mit Beeintr\u00e4chtigung der Sinneswahrnehmungen.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-einfuhrung-politik-und-gesellschaft-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-einfuhrung-politik-und-gesellschaft\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Theorie der Peer-Beratung |\n                                                            Vorlesung\n                                                            (VO)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_207<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Einf\u00fchrung Politik und Gesellschaft<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-einfuhrung-politik-und-gesellschaft\"\n                                                        aria-labelledby=\"course-einfuhrung-politik-und-gesellschaft-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Demokratie, Grundlagen einer demokratischen Gesellschaft, demokratische Insitutionen (Steiermark, \u00d6sterreich, EU, International), Sozialstruktur \u00d6sterreichs, Geschichte der Behindertenpolitiken, Diskriminierungsschutz von Menschen mit Behinderung [PELINKA, A., J. VARWICK: Grundz\u00fcge der Politikwissenschaft (2010); EICHENDROFER, E.: Geschichte des Sozialstaates in Europa, Von der &#8216;sozialen Frage&#8217; bis zur Globalisierung (2007); HALLER, M.: Die \u00d6sterreichische Gesellschaft (2008); H\u00d6GLINGER, W., et.al.: Mitgestalten! Politische Bildung und Recht f\u00fcr BMS, 1. Aufl. (2010); H\u00d6GLINGER, W., et.al.: Demokratie leben- Recht einfach, 1. Aufl. (2009)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-projektarbeit-und-prasentation-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-projektarbeit-und-prasentation\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Theorie der Peer-Beratung |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_208<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Projektarbeit und Pr\u00e4sentation<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">4.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-projektarbeit-und-prasentation\"\n                                                        aria-labelledby=\"course-projektarbeit-und-prasentation-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Peergruppenarbeit, Projektinitialisierung, Projektplanung, Projektcontrolling, Gruppendynamik in Projektgruppen, Selbstevaluation von Projektarbeiten, Abwicklung eines Kleinprojektes, \u00d6ffentlichkeitsarbeit [ANTES, W.: Projektarbeit f\u00fcr Profis (2010); MERCHEL, J.: Sozialmanagement (2013); KOTLER, P., N. R. LEE: Social Marketing f\u00fcr eine bessere Welt, Praxishandbuch f\u00fcr Politik, Unternehmen und Institutionen (2010); PUHL, R.: Klappern geh\u00f6rt zum Handwerk &#8211; Funktion und Perspektive von \u00d6ffentlichkeitsarbeit in der Sozialen Arbeit (2004);  LUTHE, D.: \u00d6ffentlichkeitsarbeit f\u00fcr Nonprofit-Organisationen, 3. Aufl. (2001)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-1063575466\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>3. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-1063575466\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-einzelsupervision-i-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-einzelsupervision-i\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Person als Werkzeug |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_301<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Einzelsupervision I<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">0.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-einzelsupervision-i\"\n                                                        aria-labelledby=\"course-einzelsupervision-i-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Einzelsupervision: Eigene Rolle, Ver\u00e4nderungen, Professionalisierung, Konfliktanalyse, Arbeit mit der \u00dcbertragung. [Schrey\u00f6gg, A.: Supervision: Ein integratives Modell. Lehrbuch zu Theorie und Praxis (2004)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-gruppensupervision-i-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-gruppensupervision-i\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Person als Werkzeug |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_306<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Gruppensupervision I<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-gruppensupervision-i\"\n                                                        aria-labelledby=\"course-gruppensupervision-i-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Gruppensupervision: Rolle als Peer-Berater_in im Praktikum, Arbeit mit KlientInnen, Offene Punkte am Ende der Ausbildung, Abschluss der Ausbildung, Sondierung. [FATZER, G. (Hg.): Supervision und Beratung, Ein Handbuch, 11. Aufl. (2005)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-praktikumsbegleitung-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-praktikumsbegleitung\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Person als Werkzeug |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_304<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Praktikumsbegleitung<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-praktikumsbegleitung\"\n                                                        aria-labelledby=\"course-praktikumsbegleitung-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Reflexion und Besprechung des Praktikums.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-exkursion-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-exkursion\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Praxis der Peer-Beratung |\n                                                            \u00dcbung\n                                                            (UE)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_305<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Exkursion<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-exkursion\"\n                                                        aria-labelledby=\"course-exkursion-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Exkursion zu einer facheinschl\u00e4gigen regionalen, nationalen oder internationalen Einrichtung zum Thema Peer-Beratung und\/oder Selbstbestimmt Leben.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-menschen-und-vielfaltunterschiedlichkeit-diversitat-und-intersektionalitat-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-menschen-und-vielfaltunterschiedlichkeit-diversitat-und-intersektionalitat\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Praxis der Peer-Beratung |\n                                                            Vorlesung\n                                                            (VO)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_302<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Menschen und Vielfalt\/Unterschiedlichkeit (Diversit\u00e4t und Intersektionalit\u00e4t)<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-menschen-und-vielfaltunterschiedlichkeit-diversitat-und-intersektionalitat\"\n                                                        aria-labelledby=\"course-menschen-und-vielfaltunterschiedlichkeit-diversitat-und-intersektionalitat-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Konzept Diversit\u00e4t, Intersektionalit\u00e4t (Behinderung und Geschlecht, Ethnie, etc.), Diversity Management im \u00f6ffentlichen und privatwirtschaftlichen Raum, Gender Mainstreaming, Fairness [DEGELE, N.: Gender \/ Queer Studies (2008); IBER, K., B., VIRTBAUER (Hg.): Diversity Management, Eine transdisziplin\u00e4re Herausforderung (2008); BOURDIEU, P.: Die verborgenen Mechanismen der Macht (2005); ANDRESEN, S., u.a. (Hg.): Gender Und Diversity: Albtraum oder Traumpaar? (2009); G\u00d6SSL, M., ua.: Diversit\u00e4t als Bildungsfaktor (2012)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-umgang-intrapersonal-mit-kritik-konflikten-und-krisen-i-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-umgang-intrapersonal-mit-kritik-konflikten-und-krisen-i\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Theorie der Peer-Beratung |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_303<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Umgang (intrapersonal) mit Kritik, Konflikten und Krisen I<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-umgang-intrapersonal-mit-kritik-konflikten-und-krisen-i\"\n                                                        aria-labelledby=\"course-umgang-intrapersonal-mit-kritik-konflikten-und-krisen-i-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Wahrnehmung von Konflikten, Konfliktinhalte und -typen: Beziehungskonflikte, Rollenkonflikte, Sachkonflikte, Wertkonflikte, Machtkonflikte, Verteilungskonflikte;  Phasenmodell der Konflikteskalation; Arten, Verlauf und Dynamik von Krisen, akute und chronische Krisen, Krise als Reaktion auf \u00dcberforderung, k\u00f6rperliche, seelische und soziale Krisen, Krise als Bedrohung f\u00fcr Systeme, Selbst- und Fremdgef\u00e4hrdung, Annahme von Kritik, Abgrenzung. [RAUCHFEISCH, U.: Menschen in psychosozialer Not, Beratung, Betreuung, Psychotherapie (1996); BONACKER, T.: Sozialwissenschaftliche Konflikttheorien: Eine Einf\u00fchrung (2005); SCHWARZ, G.: Konfliktmanagement: Konflikte erkennen, analysieren, l\u00f6sen, 8. Aufl. (2010)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-388598563\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>4. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-388598563\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-begleitseminar-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-begleitseminar\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Person als Werkzeug |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_402<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Begleitseminar<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-begleitseminar\"\n                                                        aria-labelledby=\"course-begleitseminar-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Reflexion und Besprechung des Praktikums.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-einzelsupervision-ii-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-einzelsupervision-ii\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Person als Werkzeug |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_401<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Einzelsupervision II<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">0.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-einzelsupervision-ii\"\n                                                        aria-labelledby=\"course-einzelsupervision-ii-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Einzelsupervision: Eigene Rolle, Ver\u00e4nderungen, Professionalisierung, Konfliktanalyse, Arbeit mit der \u00dcbertragung. [Schrey\u00f6gg, A.: Supervision: Ein integratives Modell. Lehrbuch zu Theorie und Praxis (2004)]\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-rechtliche-rahmenbedingungen-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-rechtliche-rahmenbedingungen\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Praxis der Peer-Beratung |\n                                                            Vorlesung\n                                                            (VO)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_406<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Rechtliche Rahmenbedingungen<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-rechtliche-rahmenbedingungen\"\n                                                        aria-labelledby=\"course-rechtliche-rahmenbedingungen-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        UN-Behindertenrechtskonvention, \u00d6-Normen, EU-Richtlinien, Gerichtsentscheide, Beschwerdewege, Schlichtungsverfahren (Sozialministerium), beg\u00fcnstigter ArbeitnehmerIn, Behindertenausweis des Sozialministeriumservice.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-umgang-intrapersonal-mit-kritik-konflikten-und-krisen-ii-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-umgang-intrapersonal-mit-kritik-konflikten-und-krisen-ii\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Praxis der Peer-Beratung |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_403<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Umgang (intrapersonal) mit Kritik, Konflikten und Krisen II<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-umgang-intrapersonal-mit-kritik-konflikten-und-krisen-ii\"\n                                                        aria-labelledby=\"course-umgang-intrapersonal-mit-kritik-konflikten-und-krisen-ii-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Pers\u00f6nliche Erfahrungen mit Sinnkrisen: Die Suche nach Lebenssinn als Lebensaufgabe\/ Formen der Sinnsuche: pers\u00f6nliche, soziale, kulturelle, historische\/ Verlusterlebnisse, pers\u00f6nliche und famili\u00e4re Verarbeitung, Trauer, Vers\u00f6hnung\/ Alter \u2013 Krankheit \u2013 Behinderungen: positive und negative Aspekte\/ Krisen als M\u00f6glichkeit des Umgangs mit Ver\u00e4nderung\/ Umgang mit dem Tod, Sterbebegleitung, pers\u00f6nlicher Zugang zu Leben, Sterben und Tod \/ Ressourcen zur Krisenbew\u00e4ltigung und Sinnfindung\/Krisen in \u00fcberg\u00e4ngen \/ Transitionsforschung, interkulturelle Krisen, Migrationskrisen \/ Lebensphasen, \u00fcberg\u00e4nge und Krisen in markanten Lebenssituationen wie Geburt, Pubert\u00e4t, Partnerwahl Elternschaft, k\u00f6rperliche und berufliche Ver\u00e4nderungen, Krankheit, Pension, Gro\u00dfelternschaft\/\u00fcberg\u00e4nge durch Migration, Wohnungs- und Milieuwechsel\/Integration der neuen, relevanten Umwelten Konfliktf\u00e4higkeit, Krisenbew\u00e4ltigung, Annahme von Kritik, Abgrenzung&#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-berufseinstieg-privatwirtschaft-offentlicher-bereich-sozialwirtschaft-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-berufseinstieg-privatwirtschaft-offentlicher-bereich-sozialwirtschaft\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Theorie der Peer-Beratung |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_404<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Berufseinstieg (Privatwirtschaft, \u00f6ffentlicher Bereich, Sozialwirtschaft<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-berufseinstieg-privatwirtschaft-offentlicher-bereich-sozialwirtschaft\"\n                                                        aria-labelledby=\"course-berufseinstieg-privatwirtschaft-offentlicher-bereich-sozialwirtschaft-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Welche Formen der professionellen T\u00e4tigkeit (regional, national und international) sind gegeben? Erarbeitung von pers\u00f6nlichen Vorstellungen, eigenen St\u00e4rken und Schwerpunkten in der Arbeit als Peer-BeraterIn.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-sexualitat-liebe-und-beziehungen-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-sexualitat-liebe-und-beziehungen\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Theorie der Peer-Beratung |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_405<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Sexualit\u00e4t, Liebe und Beziehungen<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.50<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-sexualitat-liebe-und-beziehungen\"\n                                                        aria-labelledby=\"course-sexualitat-liebe-und-beziehungen-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Sexualit\u00e4t, Liebe und Beziehungen im Rahmen von Behinderung(en), Lernschwierigkeiten und Pychiatrie-Erfahrung.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                                                                                                                                                            <div class=\"mt-5 mb-3\">\n                                                <h5>Vertiefung&nbsp;Vertiefung Menschen mit Lernschwierigkeiten:<\/h5>\n                                            <\/div>\n                                                                                                                            <button\n                                                id=\"course-vertiefung-menschen-mit-lernschwierigkeiten-praxis-in-der-beratung-beratung-begleitung-betreuung-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-vertiefung-menschen-mit-lernschwierigkeiten-praxis-in-der-beratung-beratung-begleitung-betreuung\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=41378\n                                                    >\n                                                        <span>Person als Werkzeug &#8211; Vertiefung Menschen mit Lernschwierigkeiten |\n                                                            Praktikum\n                                                            (PR)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_409<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Vertiefung Menschen mit Lernschwierigkeiten: Praxis in der Beratung (Beratung, Begleitung, Betreuung)<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">12.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-vertiefung-menschen-mit-lernschwierigkeiten-praxis-in-der-beratung-beratung-begleitung-betreuung\"\n                                                        aria-labelledby=\"course-vertiefung-menschen-mit-lernschwierigkeiten-praxis-in-der-beratung-beratung-begleitung-betreuung-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Beratung, Begleitung und\/oder Betreuung im Ausma\u00df von 15 Beratungseinheiten mit min. 3 KlientInnen. Dokumentationspflicht. Diese sind gesammelt, gebunden und mit einer abschlie\u00dfenden schriftlichen Reflexion versehen, abzugeben. Nach Einreichung der Praktikumsdokumentation findet eine kommissionelle Pr\u00fcfung \u00fcber die im Lehrgang vermittelten Inhalte und \u00fcber die abgebebene Dokumentation und schriftliche Reflexion statt.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                                                                                        <div class=\"mt-5 mb-3\">\n                                                <h5>Vertiefung&nbsp;Vertiefung Menschen mit Psychiatrieerfahrungen:<\/h5>\n                                            <\/div>\n                                                                                                                            <button\n                                                id=\"course-vertiefung-menschen-mit-psychiatrieerfahrungen-praxis-in-der-beratung-beratung-begleitung-betreuung-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-vertiefung-menschen-mit-psychiatrieerfahrungen-praxis-in-der-beratung-beratung-begleitung-betreuung\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=41374\n                                                    >\n                                                        <span>Person als Werkzeug &#8211; Vertiefung Menschen mit Psychiatrieerfahrungen |\n                                                            Praktikum\n                                                            (PR)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_408<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Vertiefung Menschen mit Psychiatrieerfahrungen: Praxis in der Beratung (Beratung, Begleitung, Betreuung)<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">12.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-vertiefung-menschen-mit-psychiatrieerfahrungen-praxis-in-der-beratung-beratung-begleitung-betreuung\"\n                                                        aria-labelledby=\"course-vertiefung-menschen-mit-psychiatrieerfahrungen-praxis-in-der-beratung-beratung-begleitung-betreuung-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Beratung, Begleitung und\/oder Betreuung im Ausma\u00df von 25 Beratungseinheiten mit min. 5 KlientInnen. Dokumentationspflicht. Diese sind gesammelt, gebunden und mit einer abschlie\u00dfenden schriftlichen Reflexion versehen, abzugeben. Nach Einreichung der Praktikumsdokumentation findet eine kommissionelle Pr\u00fcfung \u00fcber die im Lehrgang vermittelten Inhalte und \u00fcber die abgebebene Dokumentation und schriftliche Reflexion statt.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                                                                                        <div class=\"mt-5 mb-3\">\n                                                <h5>Vertiefung&nbsp;Vertiefung Menschen mit k\u00f6rperl. Behinderungen\/Beh. Sinneswahrnehmungen:<\/h5>\n                                            <\/div>\n                                                                                                                            <button\n                                                id=\"course-vertiefung-menschen-mit-korperl-behinderungenbeh-sinneswahrnehmungen-praxis-in-der-beratung-beratung-begleitung-betreuung-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-vertiefung-menschen-mit-korperl-behinderungenbeh-sinneswahrnehmungen-praxis-in-der-beratung-beratung-begleitung-betreuung\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=41370\n                                                    >\n                                                        <span>Person als Werkzeug &#8211; Vertiefung Menschen mit k\u00f6rperl. Behinderungen\/Beh. Sinneswahrnehmungen |\n                                                            Praktikum\n                                                            (PR)\n                                                            | Coursecode:\n                                                            K_PBE_2190024_407<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Vertiefung Menschen mit k\u00f6rperl. Behinderungen\/Beh. Sinneswahrnehmungen: Praxis in der Beratung (Beratung, Begleitung, Betreuung)<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">12.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">0.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-vertiefung-menschen-mit-korperl-behinderungenbeh-sinneswahrnehmungen-praxis-in-der-beratung-beratung-begleitung-betreuung\"\n                                                        aria-labelledby=\"course-vertiefung-menschen-mit-korperl-behinderungenbeh-sinneswahrnehmungen-praxis-in-der-beratung-beratung-begleitung-betreuung-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Beratung, Begleitung und\/oder Betreuung im Ausma\u00df von 25 Beratungseinheiten mit min. 5 KlientInnen. Dokumentationspflicht. Diese sind gesammelt, gebunden und mit einer abschlie\u00dfenden schriftlichen Reflexion versehen, abzugeben. Nach Einreichung der Praktikumsdokumentation findet eine kommissionelle Pr\u00fcfung \u00fcber die im Lehrgang vermittelten Inhalte und \u00fcber die abgebebene Dokumentation und schriftliche Reflexion statt.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                            \n                            <div class=\"mt-5 col-12\">\n                    <h2>Auslaufender Studienplan<\/h2>\n                <\/div>\n                                                                        <\/div>\n    <\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Die Inhalte des Lehrgangs in themenbezogene Module zusammengefasst. Eine \u00dcbersicht aller Module mit zugeh\u00f6rigen Lehrveranstaltungen finden Sie hier.<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":10000024,"menu_order":13,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.fh-joanneum.at\/akademische-peer-beraterin-akademischer-peer-berater\/academic_certificate_programme\/wp-json\/wp\/v2\/pages\/10000032"}],"collection":[{"href":"https:\/\/www.fh-joanneum.at\/akademische-peer-beraterin-akademischer-peer-berater\/academic_certificate_programme\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fh-joanneum.at\/akademische-peer-beraterin-akademischer-peer-berater\/academic_certificate_programme\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/akademische-peer-beraterin-akademischer-peer-berater\/academic_certificate_programme\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/akademische-peer-beraterin-akademischer-peer-berater\/academic_certificate_programme\/wp-json\/wp\/v2\/comments?post=10000032"}],"version-history":[{"count":0,"href":"https:\/\/www.fh-joanneum.at\/akademische-peer-beraterin-akademischer-peer-berater\/academic_certificate_programme\/wp-json\/wp\/v2\/pages\/10000032\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/akademische-peer-beraterin-akademischer-peer-berater\/academic_certificate_programme\/wp-json\/wp\/v2\/pages\/10000024"}],"wp:attachment":[{"href":"https:\/\/www.fh-joanneum.at\/akademische-peer-beraterin-akademischer-peer-berater\/academic_certificate_programme\/wp-json\/wp\/v2\/media?parent=10000032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}