{"id":96,"date":"2025-01-23T14:09:44","date_gmt":"2025-01-23T13:09:44","guid":{"rendered":"https:\/\/www.fh-joanneum.at\/european-joint-master-digital-and-sustainable-manufacturing-engineering\/master\/?page_id=96"},"modified":"2026-01-15T13:34:50","modified_gmt":"2026-01-15T12:34:50","slug":"studienplan","status":"publish","type":"page","link":"https:\/\/www.fh-joanneum.at\/european-joint-master-digital-and-sustainable-manufacturing-engineering\/master\/im-studium\/studienplan\/","title":{"rendered":"Studienplan"},"content":{"rendered":"<div\n    id=\"\"\n    class=\"wp-block-akkordeon margin-bottom-normal\"\n>\n    <div class=\"container-lg\">\n        <div class=\"row\">\n                                                <div class=\"col-12\">\n                        <h3 class=\"mb-0\">Aufbau des Masterstudiengangs <\/h3>\n\n                                                                                                                    <div class=\"accordion-element-accordion\">\n                                    <a\n                                        data-bs-toggle=\"collapse\"\n                                        class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                        href=\"#accordion-97784576\"\n                                    >\n                                        <h4\n                                            class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                            <span>1. Semester: Querschnittssemester <\/span>\n                                            <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                            <\/h5>\n                                    <\/a>\n                                    <div\n                                        class=\"collapse content-wrapper mt-4\"\n                                        id=\"accordion-97784576\"\n                                    >\n                                        <ul>\n<li>Schwerpunkt: Green and Digital Transition<\/li>\n<li>In diesem Semester werden sowohl \u00fcberfachliche als auch ingenieurspezifische Kompetenzen in den Bereichen Nachhaltigkeit und Digitalisierung vermittelt, um Sie auf die zuk\u00fcnftigen Herausforderungen in der Fertigungsindustrie vorzubereiten.<\/li>\n<\/ul>\n\n                                    <\/div>\n                                <\/div>\n                                                                                            <div class=\"accordion-element-accordion\">\n                                    <a\n                                        data-bs-toggle=\"collapse\"\n                                        class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                        href=\"#accordion-1505068658\"\n                                    >\n                                        <h4\n                                            class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                            <span>2. Semester: Spezialisierungssemester <\/span>\n                                            <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                            <\/h5>\n                                    <\/a>\n                                    <div\n                                        class=\"collapse content-wrapper mt-4\"\n                                        id=\"accordion-1505068658\"\n                                    >\n                                        <p>W\u00e4hlen Sie aus vier Spezialisierungsrichtungen, die jeweils von einem den Partnern aus dem Konsortium angeboten werden:<\/p>\n<ul>\n<li>Simulation-driven Innovation in Smart Manufacturing (Mondragon University, Spanien)<\/li>\n<li>Smart Production Engineering (FH JOANNEUM, \u00d6sterreich)<\/li>\n<li>Additive Manufacturing Technologies (KUT, Polen)<\/li>\n<li>Robotics for Manufacturing (ESTIA, Frankreich)<\/li>\n<\/ul>\n<p>Vertiefen Sie Ihr Wissen in einem dieser Spitzenbereiche und erwerben Sie spezielle F\u00e4higkeiten und Fachkenntnisse.<\/p>\n\n                                    <\/div>\n                                <\/div>\n                                                                                            <div class=\"accordion-element-accordion\">\n                                    <a\n                                        data-bs-toggle=\"collapse\"\n                                        class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                        href=\"#accordion-2048787190\"\n                                    >\n                                        <h4\n                                            class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                            <span>3. Semester: Masterarbeitssemester <\/span>\n                                            <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                            <\/h5>\n                                    <\/a>\n                                    <div\n                                        class=\"collapse content-wrapper mt-4\"\n                                        id=\"accordion-2048787190\"\n                                    >\n                                        <ul>\n<li>Schlie\u00dfen Sie Ihre Masterarbeit an der Universit\u00e4t ab, an der Sie Ihr Fachgebiet studiert haben.<\/li>\n<li>Die Masterarbeit ist ein wesentlicher Bestandteil Ihres Studiums. Sie erm\u00f6glicht es Ihnen, das Gelernte auf reale Herausforderungen anzuwenden und einen Beitrag zur laufenden Forschung in Ihrem gew\u00e4hlten Bereich zu leisten.<\/li>\n<\/ul>\n\n                                    <\/div>\n                                <\/div>\n                                                                        <\/div>\n                                    <\/div>\n    <\/div>\n<\/div>\n\n\n<div id=\"\" class=\"wp-block-links-block margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col-12\">\n                <div>\n                    <h4><\/h4>\n                    \n                <\/div>\n            <\/div>\n                            <div class=\"col-12\">\n                    <div class=\" border-bottom  border-top py-3\">\n                                                    <a href=\"https:\/\/eu4dual.education\/learn\/joint-masters\/joint-masters-sustainable-manufacturing\/\" target=\"_blank\" class=\"link arrow-link large-arrow major-text-color-hover text-decoration-none\" data-analytics=\"\" rel=\"noopener noreferrer\">\n                                <div class=\"link-content w-100\">\n                                    <div class=\"d-flex align-items-center\">\n                                        <h5 class=\"w-100 \">\n                                            Curriculum<\/h5>\n                                        <svg width=\"9\" height=\"15\" viewbox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n    <path id=\"chevron_right\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"\" stroke-width=\"1.5\" stroke-linecap=\"round\"><\/path>\n<\/svg>                                    <\/div>\n                                    <p>Mehr Informationen zum Curriculum finden Sie hier.<\/p>\n\n                                <\/div>\n                            <\/a>\n                                            <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n<div\n    id=\"\"\n    class=\"wp-block-tipp-box margin-bottom-normal\"\n>\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <div class=\"tipp-box border border-info\">\n                    <div class=\"tipp-box-inner p-2 p-md-3\">\n                        <h4 class=\"\">Hinweis<\/h4>\n                        <p>Unser Masterstudiengang umfasst 90 ECTS und wird von vier f\u00fchrenden Hochschuleinrichtungen gemeinsam angeboten. Das Programm ist in drei Semester unterteilt.<\/p>\n\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Um die vielseitige und praxisbezogene Ausbildung bestm\u00f6glich abzubilden, sind alle Inhalte des Studiums in themenbezogene Module zusammengefasst. Eine \u00dcbersicht finden Sie hier.<\/p>\n","protected":false},"author":143,"featured_media":0,"parent":9,"menu_order":20,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.fh-joanneum.at\/european-joint-master-digital-and-sustainable-manufacturing-engineering\/master\/wp-json\/wp\/v2\/pages\/96"}],"collection":[{"href":"https:\/\/www.fh-joanneum.at\/european-joint-master-digital-and-sustainable-manufacturing-engineering\/master\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fh-joanneum.at\/european-joint-master-digital-and-sustainable-manufacturing-engineering\/master\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/european-joint-master-digital-and-sustainable-manufacturing-engineering\/master\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/european-joint-master-digital-and-sustainable-manufacturing-engineering\/master\/wp-json\/wp\/v2\/comments?post=96"}],"version-history":[{"count":7,"href":"https:\/\/www.fh-joanneum.at\/european-joint-master-digital-and-sustainable-manufacturing-engineering\/master\/wp-json\/wp\/v2\/pages\/96\/revisions"}],"predecessor-version":[{"id":370,"href":"https:\/\/www.fh-joanneum.at\/european-joint-master-digital-and-sustainable-manufacturing-engineering\/master\/wp-json\/wp\/v2\/pages\/96\/revisions\/370"}],"up":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/european-joint-master-digital-and-sustainable-manufacturing-engineering\/master\/wp-json\/wp\/v2\/pages\/9"}],"wp:attachment":[{"href":"https:\/\/www.fh-joanneum.at\/european-joint-master-digital-and-sustainable-manufacturing-engineering\/master\/wp-json\/wp\/v2\/media?parent=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}