{"id":40,"date":"2024-11-06T11:09:55","date_gmt":"2024-11-06T10:09:55","guid":{"rendered":"https:\/\/www.fh-joanneum.at\/general-management\/academic_certificate_programme\/?page_id=40"},"modified":"2025-01-13T15:01:13","modified_gmt":"2025-01-13T14:01:13","slug":"beruf-und-jobchancen","status":"publish","type":"page","link":"https:\/\/www.fh-joanneum.at\/general-management\/academic_certificate_programme\/nach-dem-lehrgang\/beruf-und-jobchancen\/","title":{"rendered":"Beruf und Jobchancen"},"content":{"rendered":"<div id=\"\" class=\"wp-block-text-content margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <h3>Beruf und Jobchancen<\/h3>\n<p>Nach der akademischen Weiterbildung haben Sie Ihren Horizont um Themen der Unternehmens- und Mitarbeiterf&uuml;hrung erweitert und empfehlen sich so f&uuml;r neue berufliche Herausforderungen. Die erlernten Inhalte und Methoden k&ouml;nnen Sie sowohl bei heimischen KMUs aber auch bei internationalen Unternehmen im In- und Ausland gewinnbringend anwenden.<\/p>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mit Ihrem neu gewonnenen Know-how und Ihrer praktischen Expertise stehen Ihnen vielf\u00e4ltige berufliche M\u00f6glichkeiten und neue Karrierechancen offen. Wohin Ihre Reise geht, entscheiden Sie.<\/p>\n","protected":false},"author":143,"featured_media":89,"parent":13,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.fh-joanneum.at\/general-management\/academic_certificate_programme\/wp-json\/wp\/v2\/pages\/40"}],"collection":[{"href":"https:\/\/www.fh-joanneum.at\/general-management\/academic_certificate_programme\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fh-joanneum.at\/general-management\/academic_certificate_programme\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/general-management\/academic_certificate_programme\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/general-management\/academic_certificate_programme\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":1,"href":"https:\/\/www.fh-joanneum.at\/general-management\/academic_certificate_programme\/wp-json\/wp\/v2\/pages\/40\/revisions"}],"predecessor-version":[{"id":41,"href":"https:\/\/www.fh-joanneum.at\/general-management\/academic_certificate_programme\/wp-json\/wp\/v2\/pages\/40\/revisions\/41"}],"up":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/general-management\/academic_certificate_programme\/wp-json\/wp\/v2\/pages\/13"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/general-management\/academic_certificate_programme\/wp-json\/wp\/v2\/media\/89"}],"wp:attachment":[{"href":"https:\/\/www.fh-joanneum.at\/general-management\/academic_certificate_programme\/wp-json\/wp\/v2\/media?parent=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}