{"id":74,"date":"2024-09-10T05:30:57","date_gmt":"2024-09-10T05:30:57","guid":{"rendered":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/?page_id=74"},"modified":"2025-01-13T07:06:41","modified_gmt":"2025-01-13T07:06:41","slug":"studienplan","status":"publish","type":"page","link":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/im-studium\/studienplan\/","title":{"rendered":"Studienplan"},"content":{"rendered":"<div\n    id=\"\"\n    class=\"wp-block-curriculum margin-bottom-\"\n>\n    <div class=\"container-lg\">\n        <div class=\"row\">\n                            <div class=\"col-12\">\n                    <h2>Aktueller Studienplan<\/h2>\n                <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-8047479\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>1. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-8047479\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-contemporary-world-history-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-contemporary-world-history\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Markets 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372104<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Contemporary World History<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-contemporary-world-history\"\n                                                        aria-labelledby=\"course-contemporary-world-history-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Wichtige zeitgeschichtlichen Entwicklung, sowohl global als auch hinsichtlich ausgew\u00e4hlter Regionen und L\u00e4nder\n* Probleme und Herausforderungen von ausgew\u00e4hlten Regionen und L\u00e4ndern auf Basis ihrer geschichtlichen Entwicklung \n* Wirkung unterschiedlicher Dimensionen auf den Grad der marktwirtschaftlichen Entwicklung\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-global-markets-and-internationalisation-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-global-markets-and-internationalisation\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Markets 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372105<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Global Markets and Internationalisation<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-global-markets-and-internationalisation\"\n                                                        aria-labelledby=\"course-global-markets-and-internationalisation-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Entwicklungstheorien und Stufen der nationalen Entwicklung\n* Wichtige Merkmale und Muster der nationalen Entwicklung\n* Wichtige Daten und Fakten von ausgew\u00e4hlten Regionen und L\u00e4ndern \n* Aktuelle Dynamiken der Weltwirtschaft\n* Theorie der Globalisierung und Internationalisierungstheorien\n* Internationalisierungsstrategien und -prozesse\n* Chancen und Risiken bzw. Herausforderungen f\u00fcr multinational bzw. global t\u00e4tige Unternehmen \n* Chancen und Risiken bzw. Herausforderungen von institutionellen L\u00fccken und unterschiedlichen Rahmenbedingunen\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-international-economics-and-trade-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-international-economics-and-trade\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Markets 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372106<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>International Economics and Trade<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-international-economics-and-trade\"\n                                                        aria-labelledby=\"course-international-economics-and-trade-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Wichtige Modelle und Theorien der Mikro\u00f6konomik (Wiederholung)\n* Wichtige Modelle und Theorien der Makro\u00f6konomik (Wiederholung)\n* Wichtige internationale Au\u00dfenhandelstheorien\n* Wichtige Aspekte der internationalen Au\u00dfenhandelspolitik\n* Wichtige Modelle und Theorien zum Wirtschaftswachstum\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-international-and-transnational-law-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-international-and-transnational-law\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Markets 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372107<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>International and Transnational Law<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-international-and-transnational-law\"\n                                                        aria-labelledby=\"course-international-and-transnational-law-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Rechtliche Aspekte der internationalen Gesch\u00e4ftst\u00e4tigkeit\n* Institutionelle Aspekte der Rechtssysteme\n* \u00d6ffentliches internationales Recht\n* Transnationales Recht\n* Bilaterale Investitionsabkommen\n* Internationales Wettbewerbsrecht\n* Internationales Arbeitsrecht\n* ICSID und Schiedsverfahren\n* Geistiges Eigentum\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-strategy-business-development-and-innovation-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-strategy-business-development-and-innovation\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Strategic Management 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372101<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Strategy, Business Development and Innovation<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-strategy-business-development-and-innovation\"\n                                                        aria-labelledby=\"course-strategy-business-development-and-innovation-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Strategische Grundbegriffe\n* Strategische Analyse (intern und extern)\n* Strategiebewertung und -entwicklung \n* Strategische Entscheidungen\n* Internationalisierungstheorien\n* Business Development\n* Gesch\u00e4ftsmodelle, Innovation und Entrepreneurship\n* M&#038;A sowie strategische Partnerschaften\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-business-ethics-and-compliance-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-business-ethics-and-compliance\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Strategic Management 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372103<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Business Ethics and Compliance<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-business-ethics-and-compliance\"\n                                                        aria-labelledby=\"course-business-ethics-and-compliance-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Grundbegriffe in den Bereichen Ethik und Gesch\u00e4ftsethik\n* Grundbegriffe im Bereich Corporate Governance \n* Grundbegriffe im Bereich Compliance \n* Fehlverhalten und Korruption\n* \u2026\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-human-resources-and-business-organisation-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-human-resources-and-business-organisation\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Strategic Management 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372102<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Human Resources and Business Organisation<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-human-resources-and-business-organisation\"\n                                                        aria-labelledby=\"course-human-resources-and-business-organisation-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Grundbegriffe des HR Managements\n* Strategisches HR Management \n* Theorie der Organisation\n* Makro- vs. Mikroorganisation\n* Organisationsformen inkl. neueren und tempor\u00e4ren Formen der Organisation\n* Vor- und Nachteile verschiedener Organisationsformen\n* Interkulturelles HR Management \n* Personaleinsatz und Talent Management \n* Mitarbeiterbindung\n* Learning and Development\n* Performance Management\n* Compensation, Rewards and Benefits\n* Diversity Management\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-international-accounting-and-controlling-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-international-accounting-and-controlling\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>International Finance 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372108<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>International Accounting and Controlling<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-international-accounting-and-controlling\"\n                                                        aria-labelledby=\"course-international-accounting-and-controlling-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Basiskonzepte der internationalen Buchhaltung (IFRS)\n* Basiskonzepte der internationalen Bilanzierung\n* Grundlagen der Budgetierung\n* Grundlage des Reportings bzw. Controllings\n* Management- und Investitionsentscheidungen\n* \u2026\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-business-informatics-and-technologies-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-business-informatics-and-technologies\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Research and Informatics 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372109<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Business Informatics and Technologies<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-business-informatics-and-technologies\"\n                                                        aria-labelledby=\"course-business-informatics-and-technologies-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Fortgeschrittene Textverarbeitung\n* Fortgeschrittene Tabellenkalkulation (inkl. fortgeschrittener Formeln und Pivottabellen)\n* Grundlagen der Datenanalyse\n* Grundlagen des betrieblichen IT-Managements\n* \u00dcberblick \u00fcber wichtige Standardprogramme im betrieblichen Umfeld\n* \u00dcberblick \u00fcber Basiskonzepte der IT-Infrastruktur im Cloud-Zeitalter\n* Wichtige technologische Entwicklungen und deren Implikation f\u00fcr das betriebliche Umfeld\n* Wichtige Grundlagen hinsichtlich Data Science, Big Data und K\u00fcnstlicher Intelligenz\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-1777170644\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>2. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-1777170644\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-global-production-and-supply-chain-management-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-global-production-and-supply-chain-management\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Strategic Management 3 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372201<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Global Production and Supply Chain Management<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-global-production-and-supply-chain-management\"\n                                                        aria-labelledby=\"course-global-production-and-supply-chain-management-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Konzepte des Global Supply Chain Managements\n* Globales Sourcing und globale Beschaffung\n* Globale Produktion sowie Nachfragemanagement und Lagerverwaltung\n* Aktuelle Konzepte und Methoden der Logistik\n* Lean Supply Chain Management\n* Grundkonzepte von Industrie 4.0+\n* \u2026\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-international-marketing-pricing-and-sales-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-international-marketing-pricing-and-sales\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Strategic Management 3 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372202<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>International Marketing, Pricing and Sales<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-international-marketing-pricing-and-sales\"\n                                                        aria-labelledby=\"course-international-marketing-pricing-and-sales-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Grundlagen des Marketings und Brandings\n* Grundlagen der Marktbeobachtung bzw. der Analyse des K\u00e4uferverhaltens\n* Wichtige Marketing- und Vertriebsstrategien\n* Wichtige Strategien zur Preisgestaltung\n* \u00dcberblick \u00fcber Distributions- und Vertriebskan\u00e4le\n* Wichtige Marketing- und Vertriebskennzahlen\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-global-financial-environment-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-global-financial-environment\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>International Finance 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372203<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Global Financial Environment<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-global-financial-environment\"\n                                                        aria-labelledby=\"course-global-financial-environment-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Grundlagen der globalen Finanzm\u00e4rkte\n* Wechselkurstheorien und -risiken f\u00fcr Unternehmen\n* Relevante Hedgingstrategien und -instrumente\n* Strategien zur internationalen Finanzierung eines Unternehmens\n* Grundlagen des Treasury Managements\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-international-corporate-finance-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-international-corporate-finance\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>International Finance 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372204<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>International Corporate Finance<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-international-corporate-finance\"\n                                                        aria-labelledby=\"course-international-corporate-finance-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Analyse von Finanzberichten (Cashflow, GuV, Bilanz)\n* Grundlagen der Unternehmensbewertung\n* Grundaspekte von Projekt- und Exportfinanzierung\n* Konsolidierung von multinationalen Unternehmen\n* Erstellung von konsistenten Businesspl\u00e4nen\n* \u2026\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-research-methods-and-statistics-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-research-methods-and-statistics\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Research and Informatics 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372205<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Research Methods and Statistics<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-research-methods-and-statistics\"\n                                                        aria-labelledby=\"course-research-methods-and-statistics-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* \u00dcberblick \u00fcber qualitative und quantitative Forschungs- und Analysemethoden\n* Relevante Software-Tools f\u00fcr die Datenanalyse und das Datenmanagement\n* \u00dcberblick \u00fcber statistische Analyseverfahren\n* Grundkenntnisse von wichtigen Analyseverfahren f\u00fcr die quantitative Datenanalyse\n* Grundlagen der APA-Zitierrichtlinien\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                                                                                                                                                            <div class=\"mt-5 mb-3\">\n                                                <h5>Vertiefung&nbsp;Global AI-powered Business Evolution:<\/h5>\n                                            <\/div>\n                                                                                                                            <button\n                                                id=\"course-global-ai-powered-business-evolution-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-global-ai-powered-business-evolution\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=51178\n                                                    >\n                                                        <span>Global AI-powered Business Evolution 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372218<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Global AI-powered Business Evolution<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-global-ai-powered-business-evolution\"\n                                                        aria-labelledby=\"course-global-ai-powered-business-evolution-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Grundthemen der digitalen Transformation bzw. Evolution im betrieblichen Kontext (mit Schwerpunktsetzung auf den Einsatz der K\u00fcnstlichen Intelligenz)\n* Best Practices bzw. Case Studies im Bereich der AI-basierten digitalen Transformation bzw. Evolution\n* Typische Einsatzm\u00f6glichkeiten und Andwendungsfelder von K\u00fcnstlicher Intelligenz im betrieblichen Kontext\n* Holistische Beurteilung des Nutzens sowie der Erwartungen, der Vor- sowie Nachteile und der Chancen sowie Risiken beim betrieblichen Einsatz von K\u00fcnstlicher Intelligenz\n* Potenzial von KI f\u00fcr die grundlegende strategische Ausrichtung und F\u00fchrung eines Unternehmens\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-ai-concepts-and-technologies-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-ai-concepts-and-technologies\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=51178\n                                                    >\n                                                        <span>Global AI-powered Business Evolution 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372219<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>AI Concepts and Technologies<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-ai-concepts-and-technologies\"\n                                                        aria-labelledby=\"course-ai-concepts-and-technologies-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Grundbegriffe von Data Science, Big Data und Artificial Intelligence\n* \u00dcberblick \u00fcber wichtige Teilbereiche bzw. Str\u00f6mungen im Bereich der K\u00fcnstlichen Intelligenz (Large Language Models, Supervised Learning, Unsupervised Learning, Reinforcement Learning, &#8230;)\n* Konzeptionelle Fundamente der KI (Neuronale Netze, Statistik, &#8230;)  \n* Verzerrungen und G\u00fctekriterien hinsichtlich AI\n* Anwendung wichtiger Tools und Frameworks\n* Zukunftsperspektiven hinsichtlich AI\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-gdpr-and-ai-related-ethical-issues-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-gdpr-and-ai-related-ethical-issues\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=51178\n                                                    >\n                                                        <span>Global AI-powered Business Evolution 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372220<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>GDPR and AI-related Ethical Issues<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-gdpr-and-ai-related-ethical-issues\"\n                                                        aria-labelledby=\"course-gdpr-and-ai-related-ethical-issues-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen\n* Datenschutzrechtliche Grundbegriffe\n* Nationaler und internationaler rechtlicher Rahmen im Bereich Datenschutz\n* Datenschutzgrundverordnung sowie Rechtsdurchsetzung im Bereich Datenschutz\n* Ethische Betrachtung von Big Data und K\u00fcnstlicher Intelligenz\n* Grundlagen des IT-Risikomanagement\n&#8211; &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-business-lab-and-company-dialogue-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-business-lab-and-company-dialogue\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=51178\n                                                    >\n                                                        <span>Global AI-powered Business Evolution 3 |\n                                                            Projektarbeit\n                                                            (PA)\n                                                            | Coursecode:\n                                                            M250372221<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Business Lab and Company Dialogue<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-business-lab-and-company-dialogue\"\n                                                        aria-labelledby=\"course-business-lab-and-company-dialogue-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Praxisprojekt mit Bezug zu &#8220;Global AI-powered Business Evolution&#8221;\n* Exkursionen und\/oder Gastvortr\u00e4ge mit Bezug zu &#8220;Global AI-powered Business Evolution&#8221;\n* Projektmanagement\n* Formen der digitalen Zusammenarbeit im Team\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-756437375\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>3. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-756437375\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-accompanying-seminar-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-accompanying-seminar\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Strategic Management 4 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            M250372301<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Accompanying Seminar<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-accompanying-seminar\"\n                                                        aria-labelledby=\"course-accompanying-seminar-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Vielfalt und kulturelle Awareness\n* Pers\u00f6nliche Weiterentwicklung und interkulturelle Kommunikation\n* Reflexion \u00fcber das Auslandssemester\n* \u2026\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-global-campus-electives-1-global-strategic-management-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-global-campus-electives-1-global-strategic-management\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Strategic Management 4 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372302<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Global Campus &#8211; Electives 1: Global Strategic Management<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">10.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">0.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-global-campus-electives-1-global-strategic-management\"\n                                                        aria-labelledby=\"course-global-campus-electives-1-global-strategic-management-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Lehrveranstaltungen auf Masterlevel im Ausma\u00df von 10 ECTS an ausgew\u00e4hlten Partnerhochschulen der FH JOANNEUM aus den Bereichen (Wahlf\u00e4cher): \n* Global Strategic Management\n* Global Markets\n* International Finance\n* Research and Informatics\n* Foreign Language (max. 5 ECTS)\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                                                                                                                                                            <div class=\"mt-5 mb-3\">\n                                                <h5>Vertiefung&nbsp;Global AI-powered Business Evolution:<\/h5>\n                                            <\/div>\n                                                                                                                            <button\n                                                id=\"course-global-campus-electives-2-global-ai-powered-business-evolution-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-global-campus-electives-2-global-ai-powered-business-evolution\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=51178\n                                                    >\n                                                        <span>Global AI-powered Business Evolution 4 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            M250372309<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Global Campus &#8211; Electives 2: Global AI-powered Business Evolution<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">10.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">0.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-global-campus-electives-2-global-ai-powered-business-evolution\"\n                                                        aria-labelledby=\"course-global-campus-electives-2-global-ai-powered-business-evolution-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Lehrveranstaltungen auf Masterlevel im Ausma\u00df von 10 ECTS an ausgew\u00e4hlten Partnerhochschulen der FH JOANNEUM aus dem Gebiet &#8220;Global AI-powered Business Evolution&#8221; (Wahlf\u00e4cher)\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-project-management-and-project-work-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-project-management-and-project-work\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=51178\n                                                    >\n                                                        <span>Global AI-powered Business Evolution 4 |\n                                                            Projektarbeit\n                                                            (PA)\n                                                            | Coursecode:\n                                                            M250372310<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Project Management and Project Work<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-project-management-and-project-work\"\n                                                        aria-labelledby=\"course-project-management-and-project-work-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Individuelles Praxisprojekt mit Bezug zu &#8220;Global AI-powered Business Evolution&#8221;\n* Individuelle Exkursionen mit Bezug zu &#8220;Global AI-powered Business Evolution&#8221;\n* Projektmanagement\n* \u2026\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-930337189\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>4. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-930337189\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-advanced-topics-in-global-strategic-management-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-advanced-topics-in-global-strategic-management\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Strategic Management 5 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            M250372401<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Advanced Topics in Global Strategic Management<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-advanced-topics-in-global-strategic-management\"\n                                                        aria-labelledby=\"course-advanced-topics-in-global-strategic-management-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthema:\n* Diskussion und Reflexion ausgew\u00e4hlter aktueller und\/oder zeitloser Themen im &#8220;Global Strategic Management&#8221;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-career-development-and-assessment-training-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-career-development-and-assessment-training\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Strategic Management 5 |\n                                                            \u00dcbung\n                                                            (UE)\n                                                            | Coursecode:\n                                                            M250372403<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Career Development and Assessment Training<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-career-development-and-assessment-training\"\n                                                        aria-labelledby=\"course-career-development-and-assessment-training-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Analyse unterschiedlicher Facetten der eigenen Pers\u00f6nlichkeit\n* Pers\u00f6nliche Weiterentwicklung und Karriereplanung\n* Vorbereitung auf Assessments (insb. in einem interkulturellen Umfeld)\n* \u00dcbung der Selbstpr\u00e4sentation f\u00fcr Bewerbungsgespr\u00e4che\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-interdisciplinary-strategic-cases-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-interdisciplinary-strategic-cases\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Global Strategic Management 5 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            M250372402<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Interdisciplinary Strategic Cases<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-interdisciplinary-strategic-cases\"\n                                                        aria-labelledby=\"course-interdisciplinary-strategic-cases-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Systematische Analyse und Bewertung von Fallstudien aus ganzheitlicher bzw. strategischer Sicht\n* Ableitung, Pr\u00e4sentation und Argumentation strategischer Schlussfolgerungen und Empfehlungen\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-masters-exam-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-masters-exam\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Master&#039;s Thesis and Master&#039;s Exam |\n                                                            Modul-\/Abschlusspr\u00fcfung\n                                                            (FA)\n                                                            | Coursecode:\n                                                            M250372406<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Master&#039;s Exam<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">0.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-masters-exam\"\n                                                        aria-labelledby=\"course-masters-exam-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Pr\u00e4sentation und Verteidigung der Master&#8217;s Thesis\n* Pr\u00fcfungsgespr\u00e4ch \u00fcber studienplanrelevante Inhalte\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-masters-thesis-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-masters-thesis\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Master&#039;s Thesis and Master&#039;s Exam |\n                                                            Masterarbeit\n                                                            (MA)\n                                                            | Coursecode:\n                                                            M250372405<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Master&#039;s Thesis<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">18.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">0.50<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-masters-thesis\"\n                                                        aria-labelledby=\"course-masters-thesis-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Eigenst\u00e4ndige Durchf\u00fchrung eines Forschungsprojekts (vorzugsweise im Themenbereich der gew\u00e4hlten Fokusrichtung)\n* Eigenst\u00e4ndige Abfassung einer wissenschaftlichen Master&#8217;s Thesis\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-masters-thesis-seminar-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-masters-thesis-seminar\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Master&#039;s Thesis and Master&#039;s Exam |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            M250372404<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Englisch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Master&#039;s Thesis Seminar<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.50<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.50<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-masters-thesis-seminar\"\n                                                        aria-labelledby=\"course-masters-thesis-seminar-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Kernthemen:\n* Pr\u00e4sentation, Diskussion und Reflexion des Forschungsvorhabens bzw. des Fortschritts der eigenen Master&#8217;s Thesis\n* Pr\u00e4sentation, Diskussion und Reflexion der Forschungsfrage und -methode\n* Pr\u00e4sentation, Diskussion und Reflexion der relevanten Literatur und Quellen\n* Geben, Annehmen und Umsetzen von konstruktivem Feedback\n* &#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                            \n                    <\/div>\n    <\/div>\n<\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Um die vielseitige und praxisbezogene Ausbildung bestm\u00f6glich abzubilden, sind alle Inhalte des Studiums in themenbezogene Module zusammengefasst. Eine \u00dcbersicht finden Sie hier.<\/p>\n","protected":false},"author":143,"featured_media":0,"parent":8,"menu_order":20,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/pages\/74"}],"collection":[{"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":3,"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/pages\/74\/revisions"}],"predecessor-version":[{"id":179,"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/pages\/74\/revisions\/179"}],"up":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/pages\/8"}],"wp:attachment":[{"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/media?parent=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}