{"id":80,"date":"2024-09-10T05:57:25","date_gmt":"2024-09-10T05:57:25","guid":{"rendered":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/?page_id=80"},"modified":"2024-09-17T06:22:59","modified_gmt":"2024-09-17T06:22:59","slug":"praxisprojekte","status":"publish","type":"page","link":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/im-studium\/praxisprojekte\/","title":{"rendered":"Praxisprojekte"},"content":{"rendered":"<div id=\"\" class=\"wp-block-text-content margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <h3>Praxisprojekte<\/h3>\n<h4>Business Lab and Company Dialogue<\/h4>\n<p>Im zweiten Semester bearbeiten die Studierenden im Rahmen der Lehrveranstaltung &bdquo;Business Lab and Company Dialogue&ldquo; Projekte, welche einen klaren Bezug zum Themenbereich &bdquo;Global AI-powered Business Evolution&ldquo; und einen hohen Praxisbezug aufweisen. Im Rahmen von Projektarbeiten beziehungsweise Gruppenarbeiten, Exkursionen und \/ oder Gastvortr&auml;gen werden die Studierenden dabei unter anderem die Grundlagen des Projektmanagements wiederholen und dieses unmittelbar auch anwenden.<\/p>\n<h4>Project Management and Project Work<\/h4>\n<p>Die Studierenden sollen au&szlig;erdem w&auml;hrend ihres Auslandssemesters im dritten Semester ein Projekt durchf&uuml;hren, um ihre Projektmanagement-Kompetenz sowie interkulturelle Awareness und Kommunikation zu vertiefen. Das Projekt ist vorzugsweise mit beziehungsweise f&uuml;r ein im jeweiligen Land ans&auml;ssiges Unternehmen durchzuf&uuml;hren und soll einen klaren Bezug zur gew&auml;hlten Spezialisierung Global AI-powered Business Evolution aufweisen. Das Projekt wird grunds&auml;tzlich remote von Lehrenden der FH JOANNEUM betreut und beurteilt.<\/p>\n<p>&nbsp;<\/p>\n<h4>Master&rsquo;s Thesis, Career Development and Assessment Training<\/h4>\n<p>Im vierten Semester haben Sie die Chance, bereits w&auml;hrend des Studiums Ihren Einstieg ins Berufsleben vorzubereiten. Unser Studiengang arbeitet intensiv mit zahlreichen Unternehmen und Clustern zusammen, die regelm&auml;&szlig;ig Masterarbeiten an unsere Studierenden vergeben. Auch haben die Studierenden die Gelegenheit, im Rahmen der Lehrveranstaltung &bdquo;Career Development and Assessment Training&ldquo; eine klare Sicht auf die pers&ouml;nliche Weiterentwicklung und Karriereplanung zu entwickeln und sich in der Selbstpr&auml;sentation in Bewerbungssituationen zu erproben.<\/p>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die vielseitige Ausbildung erm\u00f6glicht Ihnen, im Studium an verschiedenen Projekten zu arbeiten. Hier erfahren Sie mehr dar\u00fcber.<\/p>\n","protected":false},"author":143,"featured_media":0,"parent":8,"menu_order":50,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/pages\/80"}],"collection":[{"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":2,"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/pages\/80\/revisions"}],"predecessor-version":[{"id":152,"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/pages\/80\/revisions\/152"}],"up":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/pages\/8"}],"wp:attachment":[{"href":"https:\/\/www.fh-joanneum.at\/global-ai-powered-business-evolution\/master\/wp-json\/wp\/v2\/media?parent=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}