{"id":36,"date":"2025-06-26T16:12:31","date_gmt":"2025-06-26T14:12:31","guid":{"rendered":"https:\/\/www.fh-joanneum.at\/guideline-based-ultrasound-blood-vessels-and-neck\/certificate_programme\/?page_id=36"},"modified":"2026-03-16T15:25:26","modified_gmt":"2026-03-16T14:25:26","slug":"team","status":"publish","type":"page","link":"https:\/\/www.fh-joanneum.at\/guideline-based-ultrasound-blood-vessels-and-neck\/certificate_programme\/im-lehrgang\/team\/","title":{"rendered":"Team"},"content":{"rendered":"<div id=\"\" class=\"wp-block-text-content margin-bottom-none\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <h3>Lehrgangsleitung<\/h3>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n<div\n    id=\"\"\n    class=\"wp-block-person-cards margin-bottom-normal\"\n>\n    <div class=\"container-lg\">\n      <div class=\"row\">\n                                                          <div class=\"col-6 col-sm-4 col-md-6 col-lg-4 col-xl-3 mb-4\">\n                    <a href=\"https:\/\/www.fh-joanneum.at\/hochschule\/person\/helmut-ritschl\"\n    class=\"person-card\">\n    <div class=\"border border-light h-100\">\n\n        <div class=\"image-wrapper\">\n            <picture>\n        <img decoding=\"async\"\n        class=\"img-fluid\"\n        src=\"https:\/\/online.fh-joanneum.at\/JOANNEUMonline\/visitenkarte.showImage?pPersonenGruppe=3&amp;pPersonenId=B87BE55B619184DD\"\n        alt=\"\"\n        title=\"\"\n                 onerror=\"this.src = 'https:\/\/www.fh-joanneum.at\/app\/themes\/fh\/public\/images\/avatar_dummy.e5edf9.png'\"     >\n<\/picture>\n\n        <\/div>\n        <div class=\"p-2 p-xl-3\">\n                            <p class=\"mb-1 hyphens\">FH-Prof. Dr.<\/p>\n                        <h6>Helmut Ritschl<\/h6>\n                            <p class=\"mb-1 hyphens\"> MA MSc<\/p>\n                        <p class=\"mb-0 hyphens\">\n              Institutsleiter\n            <\/p>\n        <\/div>\n    <\/div>\n<\/a>                  <\/div>\n                                              <\/div>\n    <\/div>\n<\/div>\n\n\n<div\n    id=\"\"\n    class=\"wp-block-team margin-bottom-normal\"\n>\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            \n            \n            \n            \n                    <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Unser kompetentes Team unterst\u00fctzt Sie bei inhaltlichen und organisatorischen Belangen. <\/p>\n","protected":false},"author":143,"featured_media":0,"parent":8,"menu_order":40,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.fh-joanneum.at\/guideline-based-ultrasound-blood-vessels-and-neck\/certificate_programme\/wp-json\/wp\/v2\/pages\/36"}],"collection":[{"href":"https:\/\/www.fh-joanneum.at\/guideline-based-ultrasound-blood-vessels-and-neck\/certificate_programme\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fh-joanneum.at\/guideline-based-ultrasound-blood-vessels-and-neck\/certificate_programme\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/guideline-based-ultrasound-blood-vessels-and-neck\/certificate_programme\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/guideline-based-ultrasound-blood-vessels-and-neck\/certificate_programme\/wp-json\/wp\/v2\/comments?post=36"}],"version-history":[{"count":3,"href":"https:\/\/www.fh-joanneum.at\/guideline-based-ultrasound-blood-vessels-and-neck\/certificate_programme\/wp-json\/wp\/v2\/pages\/36\/revisions"}],"predecessor-version":[{"id":67,"href":"https:\/\/www.fh-joanneum.at\/guideline-based-ultrasound-blood-vessels-and-neck\/certificate_programme\/wp-json\/wp\/v2\/pages\/36\/revisions\/67"}],"up":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/guideline-based-ultrasound-blood-vessels-and-neck\/certificate_programme\/wp-json\/wp\/v2\/pages\/8"}],"wp:attachment":[{"href":"https:\/\/www.fh-joanneum.at\/guideline-based-ultrasound-blood-vessels-and-neck\/certificate_programme\/wp-json\/wp\/v2\/media?parent=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}