{"id":33,"date":"2024-10-18T09:49:26","date_gmt":"2024-10-18T07:49:26","guid":{"rendered":"https:\/\/www.fh-joanneum.at\/industrial-data-science-and-ai-based-optimisation\/master\/?page_id=33"},"modified":"2025-10-28T13:13:23","modified_gmt":"2025-10-28T12:13:23","slug":"internationale-bewerberinnen-bewerber","status":"publish","type":"page","link":"https:\/\/www.fh-joanneum.at\/industrial-data-science-and-ai-based-optimisation\/master\/vor-dem-studium\/internationale-bewerberinnen-bewerber\/","title":{"rendered":"Internationale Bewerber:innen"},"content":{"rendered":"<div id=\"\" class=\"wp-block-text-content margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <h3>Zulassung<\/h3>\n<h4>Als internationale Bewerber:innen gelten:<\/h4>\n<p>Personen, die keine &ouml;sterreichische Staatsb&uuml;rgerschaft haben und<\/p>\n<ul>\n<li>aus einem EU-Staat, dem EWR, der Schweiz oder<\/li>\n<li>aus einem Drittstaat<\/li>\n<\/ul>\n<p>kommen.<\/p>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n<div id=\"\" class=\"wp-block-links-block margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col-12\">\n                <div>\n                    <h4><\/h4>\n                    \n                <\/div>\n            <\/div>\n                            <div class=\"col-12\">\n                    <div class=\" border-top py-3\">\n                                                    <a href=\"https:\/\/www.fh-joanneum.at\/international\/internationale-studierende\/vor-dem-studium\/internationale-bewerberinnen-masterstudium\/\" target=\"\" class=\"link arrow-link large-arrow major-text-color-hover text-decoration-none\" data-analytics=\"\">\n                                <div class=\"link-content w-100\">\n                                    <div class=\"d-flex align-items-center\">\n                                        <h5 class=\"w-100 \">\n                                            Informationen f&uuml;r internationale Bewerber:innen<\/h5>\n                                        <svg width=\"9\" height=\"15\" viewbox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n    <path id=\"chevron_right\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"\" stroke-width=\"1.5\" stroke-linecap=\"round\"><\/path>\n<\/svg>                                    <\/div>\n                                    <p>Informationen zu Terminen und Fristen, Kosten und mehr erhalten Sie hier.<\/p>\n\n                                <\/div>\n                            <\/a>\n                                            <\/div>\n                <\/div>\n                            <div class=\"col-12\">\n                    <div class=\" border-bottom  border-top py-3\">\n                                                    <a href=\"https:\/\/www.fh-joanneum.at\/international\/internationale-studierende\/vor-dem-studium\/\" target=\"\" class=\"link arrow-link large-arrow major-text-color-hover text-decoration-none\" data-analytics=\"\">\n                                <div class=\"link-content w-100\">\n                                    <div class=\"d-flex align-items-center\">\n                                        <h5 class=\"w-100 \">\n                                            Einreise- und Aufenthalt<\/h5>\n                                        <svg width=\"9\" height=\"15\" viewbox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n    <path id=\"chevron_right\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"\" stroke-width=\"1.5\" stroke-linecap=\"round\"><\/path>\n<\/svg>                                    <\/div>\n                                    <p>Informationen zu Einreise- und Aufenthaltsbedingungen, Orientierungsprogrammen und mehr.<\/p>\n\n                                <\/div>\n                            <\/a>\n                                            <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n<div id=\"\" class=\"wp-block-text-content margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <h4>Das m&uuml;ssen Sie au&szlig;erdem bei Ihrer Bewerbung beachten<\/h4>\n<p>Ihre Bewerbung setzt sich aus den gleichen Dokumenten zusammen, wie die von &ouml;sterreichischen Bewerberinnen und Bewerbern. Zus&auml;tzlich enth&auml;lt sie jedoch<\/p>\n<ul>\n<li>einen Nachweis &uuml;ber ausreichende Kenntnisse der englischen Sprache. Dieser Nachweis muss dem <strong>Niveau B2<\/strong> nach dem <a href=\"http:\/\/www.goethe.de\/referenzrahmen\/\" target=\"_blank\" rel=\"noopener noreferrer\">europ&auml;ischen Referenzrahmen<\/a> entsprechen und kann beispielsweise durch\n<ul>\n<li>ein <a href=\"http:\/\/www.europaeischer-referenzrahmen.de\/toefl.php\" target=\"_blank\" rel=\"noopener noreferrer\">TOEFL-Zertifikat (mindestens 87 Punkte),<\/a><\/li>\n<li>ein <a title=\"telc\" href=\"http:\/\/www.telc.net\/\" target=\"_blank\" rel=\"noopener noreferrer\">TELC-Zertifikat,<\/a><\/li>\n<li>ein <a href=\"http:\/\/www.cambridgeenglish.org\/exams\/first\/\" target=\"_blank\" rel=\"noopener noreferrer\">Cambridge-Zertifikat (First Certificate in English &ndash; FCE),<\/a><\/li>\n<li>ein <a href=\"http:\/\/www.europaeischer-referenzrahmen.de\/ielts.php\" target=\"_blank\" rel=\"noopener noreferrer\">IELTS-Zertifikat,<\/a><\/li>\n<li>ein PTE Academic Zertifikat (Pearson Test of English; mindestens 59 Punkte)<\/li>\n<li>ein &ouml;sterreichisches Maturazeugnis oder<\/li>\n<li>einen sonstigen geeigneten Schulabschluss erbracht werden.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n<div\n    id=\"\"\n    class=\"wp-block-tipp-box margin-bottom-normal\"\n>\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <div class=\"tipp-box border border-warning\">\n                    <div class=\"tipp-box-inner p-2 p-md-3\">\n                        <h4 class=\"\">Tipp<\/h4>\n                        <p>Nutzen Sie au\u00dferdem die Sprachkurse, das Orientierungsprogramm und weitere Angebote der <a title=\"Abteilung f\u00fcr internationale Beziehungen\" href=\"https:\/\/www.fh-joanneum.at\/international\/\">Abteilung f\u00fcr internationale Beziehungen<\/a>, um sich an der FH JOANNEUM einzuleben.<\/p>\n\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div id=\"\" class=\"wp-block-text-content margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <h4>Weitere Informationen<\/h4>\n<p>Unser Team der <strong>Studienberatung<\/strong> beantwortet gerne Ihre Fragen und helfen Ihnen bei der Orientierung.<\/p>\n<p>Alle<strong> Informationen zu den Beratungszeiten<\/strong> sowie die <strong>Kontaktdaten<\/strong> unserer Studienberatung <a href=\"https:\/\/www.fh-joanneum.at\/hochschule\/services\/studienberatung\/\">finden Sie hier.<\/a><\/p>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Was m\u00fcssen Studieninteressierte aus dem Ausland bei der Bewerbung beachten? Alle Bewerberinnen und Bewerber, unabh\u00e4ngig von ihrer Herkunft, haben dieselben Chancen auf einen Studienplatz. Es gibt nur wenige Unterschiede. Welche das sind, finden Sie hier.<\/p>\n","protected":false},"author":143,"featured_media":0,"parent":5,"menu_order":60,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.fh-joanneum.at\/industrial-data-science-and-ai-based-optimisation\/master\/wp-json\/wp\/v2\/pages\/33"}],"collection":[{"href":"https:\/\/www.fh-joanneum.at\/industrial-data-science-and-ai-based-optimisation\/master\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fh-joanneum.at\/industrial-data-science-and-ai-based-optimisation\/master\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/industrial-data-science-and-ai-based-optimisation\/master\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/industrial-data-science-and-ai-based-optimisation\/master\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":7,"href":"https:\/\/www.fh-joanneum.at\/industrial-data-science-and-ai-based-optimisation\/master\/wp-json\/wp\/v2\/pages\/33\/revisions"}],"predecessor-version":[{"id":192,"href":"https:\/\/www.fh-joanneum.at\/industrial-data-science-and-ai-based-optimisation\/master\/wp-json\/wp\/v2\/pages\/33\/revisions\/192"}],"up":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/industrial-data-science-and-ai-based-optimisation\/master\/wp-json\/wp\/v2\/pages\/5"}],"wp:attachment":[{"href":"https:\/\/www.fh-joanneum.at\/industrial-data-science-and-ai-based-optimisation\/master\/wp-json\/wp\/v2\/media?parent=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}