{"id":10000529,"date":"2020-12-10T14:49:26","date_gmt":"2020-12-10T12:49:26","guid":{"rendered":"https:\/\/www.fh-joanneum.at\/it-recht-und-management\/master\/?page_id=529"},"modified":"2026-04-01T09:41:08","modified_gmt":"2026-04-01T07:41:08","slug":"beruf-studium-verbinden","status":"publish","type":"page","link":"https:\/\/www.fh-joanneum.at\/it-recht-und-management\/master\/im-studium\/beruf-studium-verbinden\/","title":{"rendered":"Beruf und Studium verbinden"},"content":{"rendered":"<div id=\"\" class=\"wp-block-text-content margin-bottom-none\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <div class=\"module-migration-headline\">\n<h3>Berufsbegleitend studieren<\/h3>\n<\/div>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n<div id=\"\" class=\"wp-block-text-content margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <h4>Studienzeiten<\/h4>\n<p>Unser berufsbegleitendes Masterstudium ist optimal mit Beruf und Familie vereinbar. Der hohe E-Learning-Anteil und die damit verbundene Ortsunabh&auml;ngigkeit sind dabei wesentliche Vorteile. Die Unterrichtszeiten sind donnerstags von 18:00 bis ca. 21:30 Uhr (online) , freitags von 14:00 bis ca. 21:30 Uhr (online\/pr&auml;sent) und samstags von 08:45 bis circa 16:30 Uhr (online\/pr&auml;sent). Donnerstags wird grunds&auml;tzlich online unterrichtet, Freitage und Samstage werden in Pr&auml;senz- und Online-Einheiten aufgeteilt. F&uuml;r die E-Learning-Einheiten sind eine Breitbandverbindung und ein Headset notwendig.<\/p>\n<p>Eine Anwesenheit vor Ort ist meist an nur einem Wochenende pro Monat, Freitag und Samstag, notwendig.<\/p>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n<div id=\"\" class=\"wp-block-text-content margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <p><strong>Pr&auml;senztermine Wintersemester 2025\/2026<\/strong><\/p>\n<ul>\n<li>26. und 27.09.2025<\/li>\n<li>03. und 04.10.2025<\/li>\n<li>07. und 08.11.2025<\/li>\n<li>21. und 22.11.2025<\/li>\n<li>05. und 06.12.2025<\/li>\n<li>09. und 10.01.2026<\/li>\n<li>30. und 31.01.2026<\/li>\n<\/ul>\n<p><strong>Pr&auml;senztermine Sommersemester 2026<\/strong><\/p>\n<ul>\n<li>27. und 28.02.2026<\/li>\n<li>13. und 14.03.2026<\/li>\n<li>27. und 28.03.2026<\/li>\n<li>08. und 09.05.2026<\/li>\n<li>29. und 30.05.2026<\/li>\n<li>12. und 13.06.2026<\/li>\n<li>26. und 27.06.2026<\/li>\n<\/ul>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n<div id=\"\" class=\"wp-block-text-content margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <h4>Aufwand Selbststudium<\/h4>\n<p>Das Selbststudium h&auml;ngt immer vom Engagement und den Ambitionen unserer Studierenden ab.<\/p>\n<h4>Anwesenheit<\/h4>\n<p>W&auml;hrend den Pr&auml;senz- und Online-Zeiten gilt Anwesenheitspflicht. Im Krankheitsfall werden die Studierenden nach Vorlage einer &auml;rztlichen Best&auml;tigung entschuldigt. In letzter Instanz entscheidet die Institutsleitung &uuml;ber die Konsequenzen von Abwesenheiten sowie &uuml;ber Ausnahmen von der Anwesenheitspflicht.<\/p>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Hier erfahren Sie alles zur berufsbegleitenden Organisationsform des Studiums.<\/p>\n","protected":false},"author":11,"featured_media":10000785,"parent":10000589,"menu_order":38,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.fh-joanneum.at\/it-recht-und-management\/master\/wp-json\/wp\/v2\/pages\/10000529"}],"collection":[{"href":"https:\/\/www.fh-joanneum.at\/it-recht-und-management\/master\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fh-joanneum.at\/it-recht-und-management\/master\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/it-recht-und-management\/master\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/it-recht-und-management\/master\/wp-json\/wp\/v2\/comments?post=10000529"}],"version-history":[{"count":19,"href":"https:\/\/www.fh-joanneum.at\/it-recht-und-management\/master\/wp-json\/wp\/v2\/pages\/10000529\/revisions"}],"predecessor-version":[{"id":10000858,"href":"https:\/\/www.fh-joanneum.at\/it-recht-und-management\/master\/wp-json\/wp\/v2\/pages\/10000529\/revisions\/10000858"}],"up":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/it-recht-und-management\/master\/wp-json\/wp\/v2\/pages\/10000589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/it-recht-und-management\/master\/wp-json\/wp\/v2\/media\/10000785"}],"wp:attachment":[{"href":"https:\/\/www.fh-joanneum.at\/it-recht-und-management\/master\/wp-json\/wp\/v2\/media?parent=10000529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}