{"id":51,"date":"2024-10-17T12:10:44","date_gmt":"2024-10-17T10:10:44","guid":{"rendered":"https:\/\/www.fh-joanneum.at\/machine-learning-and-generative-ai\/master\/?page_id=51"},"modified":"2025-07-02T15:26:42","modified_gmt":"2025-07-02T13:26:42","slug":"info-kontakt","status":"publish","type":"page","link":"https:\/\/www.fh-joanneum.at\/machine-learning-and-generative-ai\/master\/vor-dem-studium\/info-kontakt\/","title":{"rendered":"Info und Kontakt"},"content":{"rendered":"<div id=\"\" class=\"wp-block-text-content margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <h3>Wo informieren Sie sich &uuml;ber Studium und Aufnahme?<\/h3>\n<h4>Wollen Sie direkt mit dem Studiengang in Kontakt treten?<\/h4>\n<p>F&uuml;r alle konkreten Fragen und Anliegen rund um das Studium stehen Ihnen die Mitarbeiter:innen des Studiengangs gerne zur Verf&uuml;gung.<\/p>\n<p><strong>FH JOANNEUM<\/strong><br>\n<strong>Studiengang Data and Information Science<\/strong><br>\n<a href=\"https:\/\/www.google.at\/maps\/place\/Eckertstra%C3%9Fe+30,+8020+Graz\/@47.0688653,15.4051188,17z\/data=!3m1!4b1!4m5!3m4!1s0x476e350efdbcf943:0x9920d33819ca900b!8m2!3d47.0688653!4d15.4073075\" target=\"_blank\" rel=\"noopener noreferrer\">Eckertstra&szlig;e 30i, 8020 Graz, AUSTRIA<\/a><br>\nE: <a title=\"Studiengang Data and Information Science per E-Mail kontaktieren\" href=\"mailto:dat@fh-joanneum.at\">dat@fh-joanneum.at<\/a><br>\nT: <a title=\"Studiengang Data and Information Science anrufen\" href=\"tel:+4331654536805\">+43 316 5453 &ndash; 6805<\/a><\/p>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n<div id=\"\" class=\"wp-block-text-content margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <h4>Haben Sie allgemeine Fragen zur FH JOANNEUM, zum Studienangebot, zu Berufschancen oder Aufnahmekriterien?<\/h4>\n<p>Die Mitarbeiter:innen unserer <strong>Studienberatung<\/strong> beantworten gerne Ihre Fragen und helfen Ihnen bei der Orientierung.<\/p>\n<p>Unser Team freut sich auf&nbsp;pers&ouml;nliche Gespr&auml;che vor Ort oder via MS Teams&nbsp;und&nbsp;Chat. Alle <strong>Informationen zu den Beratungszeiten<\/strong> sowie die <strong>Kontaktdaten<\/strong> unserer Studienberatung <a href=\"https:\/\/www.fh-joanneum.at\/hochschule\/services\/studienberatung\/\">finden Sie hier<\/a>.<\/p>\n<p><strong>Social Media:<\/strong> <a href=\"https:\/\/www.facebook.com\/fhjoanneum\/\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a> und <a href=\"https:\/\/www.instagram.com\/fh_joanneum\/?hl=de\/\/\" target=\"_blank\" rel=\"noopener noreferrer\">Instagram<\/a><\/p>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n<div id=\"\" class=\"wp-block-text-content margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <h4>Haben Sie sich bereits beworben und noch Fragen zu Ihrer Bewerbung oder zum Aufnahmeverfahren?<\/h4>\n<p>Die Mitarbeiter:innen unserer Studienadministration sind f&uuml;r die Abwicklung des Aufnahmeverfahrens zust&auml;ndig und helfen Ihnen bei Fragen diesbez&uuml;glich gerne weiter.<\/p>\n<p><strong>Studienadministration<\/strong><br>\nE: <a title=\"Studienadministration per E-Mail kontaktieren\" href=\"mailto:bewerbung@fh-joanneum.at\">bewerbung@fh-joanneum.at<\/a><br>\nT: <a title=\"Studienadministration anrufen\" href=\"tel:+4331654538923\">+43 316 5453 &ndash; 8923<\/a> oder <a title=\"Studierendenadministration anrufen\" href=\"tel:+4331654538950\">8950<\/a><\/p>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n<div id=\"\" class=\"wp-block-text-content margin-bottom-normal\">\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <h4>M&ouml;chten Sie sich vor Ort &uuml;ber das Studium informieren?<\/h4>\n<p>Mit den <strong>Open House Days<\/strong>, den Tagen der offenen T&uuml;r an der FH JOANNEUM in Graz, Kapfenberg und Bad Gleichenberg, sowie <strong>Studieren probieren<\/strong>, einer Initiative der &ouml;sterreichischen Studierendenvertretung, bieten wir Ihnen vor Ort die M&ouml;glichkeit, pers&ouml;nliche Eindr&uuml;cke zu sammeln.<\/p>\n<p>&nbsp;<\/p>\n<h5>Open House<\/h5>\n<p>Erleben Sie die Atmosph&auml;re an unserer Hochschule: Sprechen Sie direkt mit Mitarbeiterinnen und Mitarbeitern, Lehrenden und Studierenden &uuml;ber den Studienalltag, Praxisprojekte, Praktika, Auslandssemester, Berufschancen &ndash; und alles, was Sie sonst noch interessiert.<\/p>\n\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n<div\n    id=\"\"\n    class=\"wp-block-tipp-box margin-bottom-normal\"\n>\n    <div class=\"container-lg\">\n        <div class=\"row\">\n            <div class=\"col\">\n                <div class=\"tipp-box border border-warning\">\n                    <div class=\"tipp-box-inner p-2 p-md-3\">\n                        <h4 class=\"\">Tipp<\/h4>\n                        <p>Alle Termine, detaillierte Informationen und das genaue Programm zum <strong>Open House<\/strong> an jedem unserer Standorte finden Sie unter <a title=\"Open House der FH JOANNEUM\" href=\"http:\/\/www.fh-joanneum.at\/openhouse\/\">www.fh-joanneum.at\/openhouse<\/a>.<\/p>\n\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>M\u00f6chten Sie mehr \u00fcber unser Studienangebot erfahren oder haben Sie eine konkrete Frage zum Bewerbungsverfahren, zur Zulassung oder zum Studiengang? Hier finden Sie die n\u00f6tigen Informationen und die richtigen Ansprechpartner.<\/p>\n","protected":false},"author":143,"featured_media":0,"parent":6,"menu_order":80,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.fh-joanneum.at\/machine-learning-and-generative-ai\/master\/wp-json\/wp\/v2\/pages\/51"}],"collection":[{"href":"https:\/\/www.fh-joanneum.at\/machine-learning-and-generative-ai\/master\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fh-joanneum.at\/machine-learning-and-generative-ai\/master\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/machine-learning-and-generative-ai\/master\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/machine-learning-and-generative-ai\/master\/wp-json\/wp\/v2\/comments?post=51"}],"version-history":[{"count":4,"href":"https:\/\/www.fh-joanneum.at\/machine-learning-and-generative-ai\/master\/wp-json\/wp\/v2\/pages\/51\/revisions"}],"predecessor-version":[{"id":171,"href":"https:\/\/www.fh-joanneum.at\/machine-learning-and-generative-ai\/master\/wp-json\/wp\/v2\/pages\/51\/revisions\/171"}],"up":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/machine-learning-and-generative-ai\/master\/wp-json\/wp\/v2\/pages\/6"}],"wp:attachment":[{"href":"https:\/\/www.fh-joanneum.at\/machine-learning-and-generative-ai\/master\/wp-json\/wp\/v2\/media?parent=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}