{"id":10000295,"date":"2015-08-10T14:32:03","date_gmt":"2015-08-10T12:32:03","guid":{"rendered":"https:\/\/www.fh-joanneum.at\/software-design\/bachelor\/?page_id=295"},"modified":"2022-07-13T09:41:55","modified_gmt":"2022-07-13T07:41:55","slug":"studienplan","status":"publish","type":"page","link":"https:\/\/www.fh-joanneum.at\/software-design-and-cloud-computing\/berufsbegleitend\/im-studium\/studienplan\/","title":{"rendered":"Studienplan"},"content":{"rendered":"<div\n    id=\"\"\n    class=\"wp-block-curriculum margin-bottom-normal\"\n>\n    <div class=\"container-lg\">\n        <div class=\"row\">\n                            <div class=\"col-12\">\n                    <h2>Aktueller Studienplan<\/h2>\n                <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-1827915925\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>1. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-1827915925\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-linux-grundlagen-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-linux-grundlagen\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Betriebssysteme 1 |\n                                                            \u00dcbung\n                                                            (UE)\n                                                            | Coursecode:\n                                                            220418107<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Linux Grundlagen<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-linux-grundlagen\"\n                                                        aria-labelledby=\"course-linux-grundlagen-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Die Lehrveranstaltung gibt eine Einf\u00fchrung in die Aufgaben und Funktionalit\u00e4ten von Betriebssystemen allgemein und vermittelt die Bedienung einer Kommandozeilen Shell unter dem  Betriebssystems &#8220;Linux&#8221;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-netzwerktechnologien-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-netzwerktechnologien\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Betriebssysteme 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418106<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Netzwerktechnologien<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-netzwerktechnologien\"\n                                                        aria-labelledby=\"course-netzwerktechnologien-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Die Lehrveranstaltung ist eine Einf\u00fchrung in TCP\/IP-basierende Netzwerke. Spezieller Fokus wird auf das Zusammenspiel der einzelnen Protokolle\/-schichten miteinander und den Anwendungs- und Betriebssystemebenen gelegt\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-informatik-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-informatik\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Informatik 1 |\n                                                            Vorlesung\n                                                            (VO)\n                                                            | Coursecode:\n                                                            220418102<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Informatik<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-informatik\"\n                                                        aria-labelledby=\"course-informatik-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Einf\u00fchrung in die Grundbegriffe der Informatik: Daten und Informationen, Kodierungen (ASCII-Code, Unicode), Zahlensysteme (dezimal, bin\u00e4r, hexadezimal, oktal), Hardware (von Neumann Architektur), grundlegende Konzepte von Software, Programmiersprachen und Betriebssystemen, sowie weitere ausgew\u00e4hlte Kapitel der Informatik\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-mathematik-fur-informatik-i-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-mathematik-fur-informatik-i\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Informatik 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418101<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Mathematik f\u00fcr Informatik I<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-mathematik-fur-informatik-i\"\n                                                        aria-labelledby=\"course-mathematik-fur-informatik-i-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Vermittlung von mathematischer Logik (Aussagen und Pr\u00e4dikatenlogik), formale Grundlagen, Moduloarithmetik, Ermittlung von (Pseudo-)Primzahlen (Fermat, Carmichael, &#8230;), Faktorisierung, Reihenentwicklung, Relationen, Funktionen, Kombinatorik und Grundlagen der Vektorrechnung\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-datenbankdesign-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-datenbankdesign\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Software Engineering 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418103<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Datenbankdesign<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">4.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-datenbankdesign\"\n                                                        aria-labelledby=\"course-datenbankdesign-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Die Lehrveranstaltung liefert einen systematischen Zugang zum relationalen Datenbankentwurf in Theorie und Praxis (Designtools und DDL). Der Schwerpunkt liegt dabei auf dem konzeptuellen und logischen Entwurf, inklusive der Definition semantischer Bedingungen an die resultierenden Datenstrukturen. Anforderungserhebung und physischer Entwurf werden zumindest \u00fcberblicksm\u00e4\u00dfig behandelt. Weiters wird eine systematische Einf\u00fchrung in Funktion und Betrieb von Datenbankmanagementsystemen (ink. Transaktionalit\u00e4t), sowie die mit dem Datenbankentwurf in Verbindung stehenden Operationen (DDL + CRUD Befehle, etc) gegeben. Alle Themen werden von den Studierenden im begleitenden \u00dcbungsteil auch praktisch nachvollzogen.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-software-development-i-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-software-development-i\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Software Engineering 1 |\n                                                            \u00dcbung\n                                                            (UE)\n                                                            | Coursecode:\n                                                            220418105<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Software Development I<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">4.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-software-development-i\"\n                                                        aria-labelledby=\"course-software-development-i-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Inhalt sind die Grundbegriffe von prozeduraler, vor allem aber objektorientierter Programmierung, zum Beispiel: Elementare Datentypen, Variable und Konstante, Schleifen, Abfragen, Funktionen\/Methoden, Objekte und Klassen sowie einfache Datenstrukturen. Verwendung von einfachsten Bibliotheken wie zur Ein- und Ausgabe. Weiters die Verwendung von Tools zur (Compilierung und) Ausf\u00fchrung von Programmen.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-software-engineering-grundlagen-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-software-engineering-grundlagen\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Software Engineering 1 |\n                                                            Vorlesung\n                                                            (VO)\n                                                            | Coursecode:\n                                                            220418104<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Software Engineering Grundlagen<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-software-engineering-grundlagen\"\n                                                        aria-labelledby=\"course-software-engineering-grundlagen-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        \u00dcberblick \u00fcber die Prinzipien des Software Engineering: (i) Herausforderungen in der Software Entwicklung; (ii) Aktivit\u00e4ten in der Softwareentwicklung: Requirements Engineering, Design, Implementation, Verification and Validation, Software Evolution; (iii) Prozess Models: Waterfall-, Spiral-, V-Model, Component-based development, Agile Software Development.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-barcamp-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-barcamp\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Web Engineering 1 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418108<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Barcamp<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-barcamp\"\n                                                        aria-labelledby=\"course-barcamp-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Im Seminar Barcamp wird dem gesamten Jahrgang eine Aufgabenstellung zum Thema Digital Thinking gegeben. Durch Projektbasiertes Lernen (PBL) setzen sich die Studierende aktiv mit realen Problemen und Herausforderungen auseinander um ihr Wissen vertiefen. Dabei erlernen Sie branchespezifischen F\u00e4higkeiten und Kompetenzen die im Studium und im Berufsleben gesch\u00e4tzt werden. Dies umfasst die Kollaboration in diversen Teams, kritisches Denken und Kommunikation und Reflexion in eine praxisnahem Umfeld.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-webtechnologien-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-webtechnologien\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Web Engineering 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418109<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Webtechnologien<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-webtechnologien\"\n                                                        aria-labelledby=\"course-webtechnologien-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Die Vorlesung ist eine Einf\u00fchrung in Webtechnologien mit den Schwerpunkten:  \u2022 Hypertext, Hypermedia, Informationssysteme, WWW, Social Web, Semantic Web, Suchmaschinen  \u2022 Web Design, Web Usability und Accessibility  \u2022 Hypertext Markup Language &#8211; HTML5  \u2022 Farbmodelle und webkonforme Bildformate  \u2022 Cascading StyleSheets und Javascript Einf\u00fchrung  \u2022 CSS basierte responsive Web-Layouts Die \u00dcbung behandelt die Erstellung von standardkonformen Webseiten mit HTML5, CSS und Javascript sowie die Grundtechniken der webkonformen Bildbearbeitung.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-rechtsgrundlagen-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-rechtsgrundlagen\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 1 |\n                                                            Vorlesung\n                                                            (VO)\n                                                            | Coursecode:\n                                                            220418110<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Rechtsgrundlagen<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-rechtsgrundlagen\"\n                                                        aria-labelledby=\"course-rechtsgrundlagen-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Da in der Praxis eine Vielzahl von Vertragsinhalten von Nichtjuristen stammen, sollen im Rahmen der LV  den Studierenden die Grundlagen des Vertragsrechtes vermittelt werden. Schwerpunkte sind: Allgemeine Grundlagen des Vertragsrechts &#8211; Bedeutung m\u00fcndlicher Absprachen &#8211; Schweigen im Rechtsverkehr &#8211; Angebot\/Annahme &#8211; Gew\u00e4hrleistung\/Garantie, Eigentumsfragen, Haftungsvermeidung.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-teamentwicklung-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-teamentwicklung\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 1 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418112<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Teamentwicklung<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-teamentwicklung\"\n                                                        aria-labelledby=\"course-teamentwicklung-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Phasen der Teamentwicklung; Reflexion von Erfolgsfaktoren f\u00fcr erfolgreiche Teams. Prozesse der Teambildung. Zusammenwirkung von unterschiedlichen Teamrollen und Teammitgliedern. Methoden zur Konfliktbew\u00e4ltigung und zum Konfliktmanagement. Rollenspiele.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-okonomische-grundlagen-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-okonomische-grundlagen\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 1 |\n                                                            Vorlesung\n                                                            (VO)\n                                                            | Coursecode:\n                                                            220418111<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>\u00d6konomische Grundlagen<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-okonomische-grundlagen\"\n                                                        aria-labelledby=\"course-okonomische-grundlagen-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Grunds\u00e4tzliches zum Begriff &#8220;Wirtschaften&#8221;; Punktuelle Darstellung volkswirtschaftlicher Zusammenh\u00e4nge; Praktische Darstellung von buchhalterischen und kostenrechnungstechnischen Zusammenh\u00e4ngen, Grunds\u00e4tze der Steuerlehre\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-1978215468\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>2. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-1978215468\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-linuxunix-systemmanagement-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-linuxunix-systemmanagement\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Betriebssysteme 2 |\n                                                            \u00dcbung\n                                                            (UE)\n                                                            | Coursecode:\n                                                            220418207<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Linux\/Unix Systemmanagement<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-linuxunix-systemmanagement\"\n                                                        aria-labelledby=\"course-linuxunix-systemmanagement-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Die Lehrveranstaltung vermittelt die fundamentalen, wichtigen Aufgaben der Linux System- und Netzwerk Administration.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-netzwerkmanagement-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-netzwerkmanagement\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Betriebssysteme 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418206<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Netzwerkmanagement<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-netzwerkmanagement\"\n                                                        aria-labelledby=\"course-netzwerkmanagement-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Diese integrierte Lehrveranstaltung stellt eine Vertiefung in die lokalen Netzwerke dar. Es werden der\/dem Teilnehmer\/in die Themen Switching und Routing im LAN n\u00e4her gebracht. Weiters wird das Thema Virtuelle LAN&#8217;s erl\u00e4utert und eine vertiefte Einf\u00fchrung in Technologien wie MPLS und IPv6 geboten.   \u2022 Wireless LAN \u2022 Switching im LAN \u2022 Routing im LAN \u2022 Virtuelle LANs \u2022 MPLS \u2022 Vertiefung IPv6\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-datenstrukturen-und-algorithmen-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-datenstrukturen-und-algorithmen\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Informatik 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418202<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Datenstrukturen und Algorithmen<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-datenstrukturen-und-algorithmen\"\n                                                        aria-labelledby=\"course-datenstrukturen-und-algorithmen-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Einf\u00fchrung in elementare Datenstrukturen und Algorithmen:  Formale Eigenschaften von Algorithmen, Effizienzbestimmung, lineare Listen, Schlangen, Stapel, Sortierverfahren, Suchverfahren, Hashing, B\u00e4ume, Graphen\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-mathematik-fur-informatik-ii-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-mathematik-fur-informatik-ii\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Informatik 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418201<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Mathematik f\u00fcr Informatik II<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-mathematik-fur-informatik-ii\"\n                                                        aria-labelledby=\"course-mathematik-fur-informatik-ii-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Dieser Kurs vermittelt ein Verst\u00e4ndnis f\u00fcr die besondere Problematik bei der Behandlung mathematischer Aufgaben auf dem Digitalrechner. Die Kenntnis grundlegender numerischer Methoden zur Probleml\u00f6sung wie Interpolation, Approximation und linearer Gleichungssysteme unter Ber\u00fccksichtigung von Randbedingungen (Fehler, Effizienz) ist die Basis f\u00fcr die Fertigkeit zum Entwurf und zur Analyse numerischer Algorithmen.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-bootcamp-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-bootcamp\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Software Engineering 2 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418204<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Bootcamp<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-bootcamp\"\n                                                        aria-labelledby=\"course-bootcamp-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Im Seminar Bootcamp erarbeiten Studierende in Teams konkrete L\u00f6sungen f\u00fcr digitale Problemstellungen. Dieser Challenge Based Lehr- und Lernansatz regt die Studierenden dazu an, jene Technologien die im Studium zum Einsatz kommen zur L\u00f6sung realer Probleme einzusetzen. Das Seminar Bootcamp ist kooperativ und praxisorientiert und fordert die Studierenden auf, mit Peers, Lehrenden und ExpertInnen, um gute Fragen zu stellen, tieferes Fachwissen zu entwickeln, Ma\u00dfnahmen zu ergreifen, Herausforderungen anzunehmen und zu l\u00f6sen, aktiv zu werden und ihre Erfahrungen zu teilen.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-relationale-datenbanken-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-relationale-datenbanken\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Software Engineering 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418203<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Relationale Datenbanken<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-relationale-datenbanken\"\n                                                        aria-labelledby=\"course-relationale-datenbanken-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Die relationale Theorie sowie die relationalen Operationen und ihre Anwendung in Form von SQL-Queries stehen im Zentrum dieser Lehrveranstaltung. Aufbauend auf den im vorigen Semester erstellten Datenstrukturen und Datenbest\u00e4nden werden nun Abfragen in allen Formen und Komplexit\u00e4ten studiert und ge\u00fcbt. Weitere Themen sind Mehrbenutzersynchronisation, prozedurale Erweiterungen von SQL sowie objektrelationale Konzepte.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-software-development-ii-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-software-development-ii\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Software Engineering 2 |\n                                                            \u00dcbung\n                                                            (UE)\n                                                            | Coursecode:\n                                                            220418205<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Software Development II<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">4.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-software-development-ii\"\n                                                        aria-labelledby=\"course-software-development-ii-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Inhalt sind die objektorientierte Programmierung inklusive zum Beispiel: Exception Handling, Scope, Datenstrukturen (Listen und Maps), Interfaces, Ableitung. Verwendung von ausgew\u00e4hlten Bibliotheken. Umsetzung von Strukturierung bzw. Modularisierung von Softwarepaketen und weiters Tools f\u00fcr Deployment.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-human-computer-interaction-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-human-computer-interaction\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Web Engineering 2 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418209<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Human Computer Interaction<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-human-computer-interaction\"\n                                                        aria-labelledby=\"course-human-computer-interaction-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Das Design von gebrauchstauglichen User Interfaces wird anhand grundlegender Gestaltungsprinzipien, Methoden und Werkzeugen vorgestellt. Die Studierenden erlernen die theoretischen Grundlagen und auch die praktische Anwendung von Usability Engineering. Das erlernte Wissen wird in Form einer praktischen Seminararbeit vertieft.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-web-engineering-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-web-engineering\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Web Engineering 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418208<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Web Engineering<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-web-engineering\"\n                                                        aria-labelledby=\"course-web-engineering-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Aufbauend auf dem ersten Semester werden die Kenntnisse von Webtechnologien vertieft. Dabei werden folgende Inhalte behandelt: XML, DTD,XSD, XSL(T) und XPath Strukturierte Dokumente, Grundkonzepte von Auszeichnungssprachen am Beispiel von XML,  Dokumententypdefinition (DTD), XML Schema Definitions (XSD), Unterscheidung &#8220;well-formed&#8221; \/ &#8220;valid&#8221;, Verarbeitung von XML-Dokumenten mit XSL: Verarbeitungsmodell von XSLT, \u00fcbersicht \u00fcber Standard-APIs zur Verarbeitung von XML-Daten, XML als Basis f\u00fcr Datenspeicherung und Datenaustausch, XML-Anwendungsbeispiele aus verschiedenen Bereichen (z.B. Multimedia, (Mobil)kommunikation Clientseitige Scriptsprachen (Beispiel: Javascript) Grundlagen, Events und Steuerung von Webinhalten, DOM Manipulation, Asysnchroner Datenaustausch f\u00fcr interactive Webanwendungen und Basiswissen f\u00fcr Rich Internet Applications (RIA) mit AJAX, Kombination mit XML Serverseitige Scriptsprachen (Beispiel: PHP)&#8230;\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-it-industry-english-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-it-industry-english\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 2 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418210<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>IT Industry English<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-it-industry-english\"\n                                                        aria-labelledby=\"course-it-industry-english-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Erarbeitung studiengangs- und berufsspezifischer Themenbereiche; Schulung des Lese- und H\u00f6rverst\u00e4ndnisses anhand authentischer Materialien, wobei die Erweiterung des Wortschatzes im Vordergrund steht. Kritische Auseinandersetzung und Beleuchtung aktueller Entwicklungen im Bereich IT, IT Security, Software Development und New Media.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-unternehmensfuhrung-und-organisation-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-unternehmensfuhrung-und-organisation\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 2 |\n                                                            Vorlesung\n                                                            (VO)\n                                                            | Coursecode:\n                                                            220418211<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Unternehmensf\u00fchrung und Organisation<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-unternehmensfuhrung-und-organisation\"\n                                                        aria-labelledby=\"course-unternehmensfuhrung-und-organisation-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Organisationslehre, Gliederung der Aufbau- und Ablauforganisation; strategische Unternehmensf\u00fchrung, Unternehmensplanung, F\u00fchrungsstile, Personalmanagement\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-957898970\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>3. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-957898970\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-cloud-technologien-1-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-cloud-technologien-1\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Cloud Computing 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418305<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Cloud Technologien 1<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-cloud-technologien-1\"\n                                                        aria-labelledby=\"course-cloud-technologien-1-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        In dieser Lehrveranstaltung lernen Studierende die Definition und Charakteristika von Cloud Computing, Service- und Bereitstellungs-Modellen kennen. Studierenden wird ein Einblick in die Technologien, die zum Erstellen, Vertreiben und Warten von virtuellen Maschinen und Anwendungen in der Cloud ben\u00f6tigt werden gegeben. Studierende nutzen cloud-basierte Infrastrukturen f\u00fcr existierende und neue Dienste. Zu diesem Zweck dienen \u201ePublic Cloud Services\u201c und Open Source \u00c4quivalente. Des Weiteren untersuchen Studierende APIs (Application Programming Interfaces), welche von den wichtigsten \u00f6ffentlichen Cloud Betreibern angeboten werden. Sie entwickeln Anwendungen mittels hoch verf\u00fcgbarer Cloud-Infrastrukturen und RESTful Webservices. Au\u00dferdem wird gezeigt, wie eine Anbindung an die traditionelle IT-Infrastruktur (z.B. VPN Cloud-System, Directory-Info Abgleich, etc.) umgesetzt und \u201eOn-Premise\u201c L\u00f6sungen zu \u201eSoftware as a Service\u201c (SaaS) (\u201eOff Premise\u201c) ausgelagert werden k\u00f6nnen.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-servertechnologien-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-servertechnologien\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Cloud Computing 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418303<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Servertechnologien<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-servertechnologien\"\n                                                        aria-labelledby=\"course-servertechnologien-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Im Rahmen dieser Lehrveranstaltung werden die wichtigsten Servertechnologien sowohl theoretisch als auch praktisch behandelt. Der Zweck des Gegenstandes ist das Vertraut-werden mit Servertechnologien und Servern, deren Dienste (fast) allt\u00e4glich in Anspruch genommen werden. \u2022 Domain Name System (DNS)  \u2022 Dynamic Host Configuration Protocol (DHCP) \u2022 Hyper Text Transfer Protocol (HTTP), Apache Webserver Common Gateway Interface (CGI), Secure Socket Layer (SSL), Certificates, Additional modules and configurations  \u2022 Simple Mail Transfer Protocol (SMTP) &#038; Security (TLS) \u2022 Post Office Protocol (POP), Internet Message Access Protocol (IMAP) \u2022 File Systems &#038; Services in the Internet.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-big-data-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-big-data\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Machine Learning 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418304<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Big Data<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-big-data\"\n                                                        aria-labelledby=\"course-big-data-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Die Lehrveranstaltung bietet eine anwendungsorientierte Einf\u00fchrung in Big Data Datenmodelle und Architekturen. Anschlie\u00dfend werden Storage und Datenbanksysteme im Umfeld Big Data anhand praxisnaher \u00dcbungsszenarien erprobt und studiert. Dabei wird insbesondere Wert auf die Erarbeitung von Schnittstellen und Anbindungsm\u00f6glichkeiten zu aktuelle Software-Technologien gelegt. Weiterf\u00fchrende Themen, die abschlie\u00dfend anhand von praktischen \u00dcbungen erarbeitet werden, sind unter anderem Big Data Views und Queues, Performance und Tuning. Besondere Sorge wird daf\u00fcr getragen, der Diskussion aktueller technologischer Entwicklungen im Bereich Big Data gen\u00fcgend Raum zu geben.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-visualisierung-und-datamining-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-visualisierung-und-datamining\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Machine Learning 1 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418306<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Visualisierung und Datamining<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">4.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-visualisierung-und-datamining\"\n                                                        aria-labelledby=\"course-visualisierung-und-datamining-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Einf\u00fchrung in die wichtigsten statistischen Verfahren. Grundlagen des Datamining (unter anderem Clustering, Klassifikation, Regression). Im Bereich Visualisierung werden Handling und Plotting von Daten ebenso wie statische und interaktive Visualisierungen behandelt. In der \u00dcbung werden diese Verfahren mittels aktueller Softwarepakte anwendungsorientiert behandelt.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-software-design-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-software-design\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Software Engineering 3 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418301<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Software Design<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">4.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-software-design\"\n                                                        aria-labelledby=\"course-software-design-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Einf\u00fchrung in objekt-orientiertes Software Design: (i) Modellierung von Software Systemen mit UML;  (ii) Einf\u00fchrung in Design- Patterns; (iii) Refactoring with Design-Patterns\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-software-quality-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-software-quality\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Software Engineering 3 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418302<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Software Quality<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">4.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-software-quality\"\n                                                        aria-labelledby=\"course-software-quality-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Praxisbezogene Ans\u00e4tze zur Verbesserung der Software Qualit\u00e4t: Debugging, Software Inspection, Software Testing (Unit-, Integration-, System-, Performance-Tests), Test Case Design, Verification and Validation in the Software Development Process.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-hackathon-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-hackathon\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Web Engineering 3 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418309<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Hackathon<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">4.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-hackathon\"\n                                                        aria-labelledby=\"course-hackathon-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Im Seminar Hackathon arbeiten die Studierenden an einer ausgew\u00e4hlten, digitale Problemstellungen. Dabei arbeiten die teilnehmenden Teams innerhalb einer begrenzten Zeitspanne um ein Proof-of-Concept f\u00fcr eine L\u00f6sung f\u00fcr ein bestimmtes Problem bzw. eine bestimmte Herausforderung zu entwickeln oder zu entwerfen. Dabei werden die Phasen der Zusammenarbeit wie folgt festgelegt Engage &#8211; Investigate &#8211; Act.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-web-application-development-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-web-application-development\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Web Engineering 3 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418308<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Web Application Development<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-web-application-development\"\n                                                        aria-labelledby=\"course-web-application-development-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Design und Umsetzung von Rich Internet Applications (RIAs) mit dem Schwerpunkt auf Webapplikationen f\u00fcr mobile Ger\u00e4te mit unterschiedlichen Displaygr\u00f6\u00dfen inklusive offline Funktionalit\u00e4t. Neben semantischen HTML5 Tags und Canvas\/SVG Animationen wird weiters der Schwerpunkt auf verschiedene JavaScript APIs zum Beispiel zur Unterst\u00fctzung von Sensoren, von Location Based Services oder Web Sockets f\u00fcr Real Time Communication gelegt. Auch sind Analyse und Optimierung von Performance sowie automatisiertes Unit und User Interface Testing von Relevanz.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-prozess-und-qualitatsmanagement-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-prozess-und-qualitatsmanagement\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 3 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418307<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Prozess- und Qualit\u00e4tsmanagement<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-prozess-und-qualitatsmanagement\"\n                                                        aria-labelledby=\"course-prozess-und-qualitatsmanagement-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Einf\u00fchrung zum Thema Gesch\u00e4ftsprozesse; Entwicklung in der Organisationslehre im 20. Jhdt; Definition von Gesch\u00e4ftsprozessen; Prozessanalyse-Istaufnahme-Istanalyse; Gestaltung der Arbeit &#8211; die tayloristische Arbeitsstruktur; Optimierung von Gesch\u00e4ftsprozessen, Business Process Reengineering, Gesch\u00e4ftsprozessmodellierung, Prozesscontrolling Benchmarking von Prozessen.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-2065145894\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>4. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-2065145894\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-cloud-technologien-2-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-cloud-technologien-2\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Cloud Computing 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418407<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Cloud Technologien 2<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-cloud-technologien-2\"\n                                                        aria-labelledby=\"course-cloud-technologien-2-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Die Lehrveranstaltung vermittelt die Grundlagen f\u00fcr den Betrieb privater Cloud L\u00f6sungen. Die Studierenden lernen dabei die technischen Konzepte und Anforderungen, die die technologische Basis f\u00fcr die verschiedenen Cloud Service Modellen bilden, kennen: Infrastruktur Virtualisierung, Object Storage Implementierungen, Application Container Runtime Environments und Application Container Cluster, Serverless Computing, sowie Methoden f\u00fcr das Management des Lifecycles von Cloud Applikationen\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-machine-learning-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-machine-learning\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Machine Learning 2 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418408<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Machine Learning<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-machine-learning\"\n                                                        aria-labelledby=\"course-machine-learning-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Zu Beginn der Lehrveranstaltung werden die Grundlagen von Data Retrieval und Preparation, insbesondere Data Cleansing Methoden vorgestellt. Nach einem \u00dcberblick \u00fcber den Data Analytics Life-Cycle erfolgt die Erarbeitung grundlegender Datenanalytischer Methoden wie etwa Clustering, Associations, Regression, Classification, Time Series Analysis, Text Analysis, Map Reduce und Statistical Methods. Nach der Erarbeitung von Datamining Grundlagen (Abstands- und \u00c4hnlichkeitsma\u00dfe, neuronale Netze, Wissensrepresentation, Textmining, Webmining) erfolgt eine abschlie\u00dfende Diskussion von Basistechniken der Datenvisualisierung, sowie aktueller Entwicklungen und Technologien.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-design-patterns-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-design-patterns\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Software Engineering 4 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418409<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Design Patterns<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">4.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-design-patterns\"\n                                                        aria-labelledby=\"course-design-patterns-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Ausbau der Kentnisse im objekt-orientierten Design durch den Einsatz von Design Patterns: (i) Object-Oriented Design Principles;  (ii) Creational Patterns; (iii) Structural Patterns; (iv) Behavoioral Patterns; (v) Design Patterns in Practice.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-software-architectures-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-software-architectures\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Software Engineering 4 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418411<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Software Architectures<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">4.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-software-architectures\"\n                                                        aria-labelledby=\"course-software-architectures-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Einf\u00fchrung in die technischen Aspekte von Software Architecturen anhand von Architektur-Prototypen: (i) Layered Architectures; (ii) Distributed Architectures; (iii) Component-Based Architectures; (iv) Service-Oriented Architectures; (v) Analyse aktueller Trends im Bereich Software Architekturen\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-startup-project-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-startup-project\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Startup Project 1 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418401<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Startup Project<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-startup-project\"\n                                                        aria-labelledby=\"course-startup-project-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Im Seminar Startup geht es darum digitale L\u00f6sungen nachhaltig zu machen. Die Studierenden k\u00f6nnen in Kleingruppen ausgehend von einer Idee einen Prototyp konzipieren, entwerfen, implementieren, dokumentieren und pr\u00e4sentieren. Dar\u00fcber hinaus k\u00f6nnen sie die Zusammenarbeit, Lernfortschritte, das Arbeitsergebnis und die Dokumentation kritisch evaluieren und reflektieren.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-interactive-mobile-applications-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-interactive-mobile-applications\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Web Engineering 4 |\n                                                            \u00dcbung\n                                                            (UE)\n                                                            | Coursecode:\n                                                            220418410<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Interactive Mobile Applications<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-interactive-mobile-applications\"\n                                                        aria-labelledby=\"course-interactive-mobile-applications-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Im Rahmen dieser Lehrveranstaltung werden die wichtigsten Servertechnologien sowohl theoretisch als auch praktisch behandelt. Der Zweck des Gegenstandes ist das Vertraut-werden mit Servertechnologien und Servern, deren Dienste (fast) allt\u00e4glich in Anspruch genommen werden. \u2022 Domain Name System (DNS)  \u2022 Dynamic Host Configuration Protocol (DHCP) \u2022 Hyper Text Transfer Protocol (HTTP), Apache Webserver Common Gateway Interface (CGI), Secure Socket Layer (SSL), Certificates, Additional modules and configurations  \u2022 Simple Mail Transfer Protocol (SMTP) &#038; Security (TLS) \u2022 Post Office Protocol (POP), Internet Message Access Protocol (IMAP) \u2022 File Systems &#038; Services in the Internet.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-web-service-development-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-web-service-development\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Web Engineering 4 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418403<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Web Service Development<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-web-service-development\"\n                                                        aria-labelledby=\"course-web-service-development-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Die Lehrveranstaltung beleuchtet die Grundlagen von dynamischen Web Seiten. Anhand einfacher Web Applikationen werden die Grundlagen der Zugriffsprotokolle und deren M\u00f6glichkeiten (HTTP, Request\/Response), Sessionverwaltung (Cookies, Server-Session-Objekte), dynamisch Seiten-\/Contenterstellung (Mimetypes, HTML, CSS, XML, Images), Eingaben (Formulare, Parameter,) Up-und Download (auch Bin\u00e4rfiles) sowie einfache Backendfunktionalit\u00e4t am Server (Mailversand, Datenbankzugriff) erarbeitet. Weiters wird die grundlegende Funktionsweise von interaktiven, also lokal dynamischen Seiten mit JavaScript bzw. asynchronem Zugriff auf den Server (AJAX) vermittelt.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-it-recht-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-it-recht\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 4 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418405<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>IT-Recht<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-it-recht\"\n                                                        aria-labelledby=\"course-it-recht-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Einf\u00fchrung der Studierenden in die rechtlichen Grundlagen des eBusiness. Dabei wird zun\u00e4chst ein \u00dcberblick \u00fcber einzelne Rechtsfragen gebracht, die in eBusiness Projekten relevant sind (Domain Namen, E-Commerce-Gesetz, Urheberrecht, Signaturrecht etc). Danach wird ein Schwerpunkt rund um das Thema Urheberrecht im eBusiness gelegt (Schutz von Software, Websites, Datenbanken etc).\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-meetings-and-negotiations-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-meetings-and-negotiations\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 4 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418404<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Meetings and Negotiations<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-meetings-and-negotiations\"\n                                                        aria-labelledby=\"course-meetings-and-negotiations-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Ausbau und Vertiefung von Schl\u00fcsselkompetenzen: Erarbeitung der f\u00fcr Verhandlungen und Gesch\u00e4ftstreffen ben\u00f6tigten Fachsprache; Planung, Aufbau und Durchf\u00fchrung von Meetings anhand von Simulationen. Bewerbungstrainng, Interviews und Assessment Centers.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-online-marketing-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-online-marketing\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 4 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418406<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Online Marketing<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-online-marketing\"\n                                                        aria-labelledby=\"course-online-marketing-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Aufbau, Festigung, Vertiefung und Ausbau des Marketing und PR Wissens; Studierende kennen die verschiedenen Funktionen des Online Marketing und sind in der Lage, die Lerninhalte miteinander zu verkn\u00fcpfen und an praktischen Beispielen zu erarbeiten.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-projektmanagement-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-projektmanagement\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 4 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418402<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Projektmanagement<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-projektmanagement\"\n                                                        aria-labelledby=\"course-projektmanagement-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Folgende Teilbereiche werden n\u00e4her betrachtet:  Definition von Projekten Projektarten und deren Kategorisierung Projektmanagement Phasenmodell Management von Projekten\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-1556787785\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>5. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-1556787785\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-bachelorarbeit-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-bachelorarbeit\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Bachelorarbeit |\n                                                            Bachelorarbeit\n                                                            (BA)\n                                                            | Coursecode:\n                                                            220418501<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Bachelorarbeit<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">10.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">0.33<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-bachelorarbeit\"\n                                                        aria-labelledby=\"course-bachelorarbeit-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Selbstst\u00e4ndige Bearbeitung eines vorgegebenen Themas oder eines Themas in Kooperation mit einem Unternehmen aus dem Bereich der unterschiedlichen Module des Bachelorstudiums mit wissenschaftlichen Methoden. Die Arbeit leistet einen Beitrag zur L\u00f6sung der Aufgabenstellungen und stellt die Ergebnisse verst\u00e4ndlich dar.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-seminar-zur-bachelorarbeit-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-seminar-zur-bachelorarbeit\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Bachelorarbeit |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418502<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Seminar zur Bachelorarbeit<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-seminar-zur-bachelorarbeit\"\n                                                        aria-labelledby=\"course-seminar-zur-bachelorarbeit-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Das Seminar befasst sich mit der wissenschaftlichen Strukturierung und Ausformulieren der Abschlussarbeit zum Bachelorstudium. Die StudentInnen weisen mit den Bachelorarbeiten die im Studium erworbene F\u00e4higkeit nach, fachspezifische Aufgabenstellung zu bearbeiten und zu l\u00f6sen.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-it-security-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-it-security\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>IT Security |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418504<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>IT Security<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-it-security\"\n                                                        aria-labelledby=\"course-it-security-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Die Studierenden erfahren Methoden zur praktischen Umsetzung von Sicherheitsl\u00f6sungen auf verschiedenen Ebenen von IT-Systemen, basierend auf naturwissenschaftlich-technischen Fundierungen wie beispielsweise Kryptografie bzw. IT-Basistechnologien (Netzwerk-, Servertechnologien, Programmierung).\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-research-skills-practices-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-research-skills-practices\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>IT Security |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418503<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Research Skills &amp; Practices<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-research-skills-practices\"\n                                                        aria-labelledby=\"course-research-skills-practices-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Verbesserung der Kenntnisse und Fertigkeiten f\u00fcr das wissenschaftliche Arbeiten: Verfassen verschiedener Textsorten (besonderes Augenmerk wird auf das Schreiben von Abstracts und Zusammenfassungen gelegt); Erwerben von Strategien f\u00fcr das Verstehen und selbstst\u00e4ndige Erstellen von komplexen, wissenschaftlichen Texten; Erweiterung des Wortschatzes im Bereich wissenschaftliches Schreiben (Academic Vocabulary); Einf\u00fchrung in Pr\u00e4sentationstechniken: Zusammenfassen und Pr\u00e4sentieren wissenschaftlicher Arbeiten (zum Beispiel von Projektarbeiten und Bachelorarbeiten)\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-programmierkonzepte-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-programmierkonzepte\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Web Engineering 5 |\n                                                            \u00dcbung\n                                                            (UE)\n                                                            | Coursecode:\n                                                            220418506<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Programmierkonzepte<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-programmierkonzepte\"\n                                                        aria-labelledby=\"course-programmierkonzepte-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        \u00dcbersicht \u00fcber Programmiersprachen. Compiler und Linker im Vergleich zu Interpreter. Dynamische vs. statische Programmiersprachen. Speicherverwaltung und Pointerarithmetik. Automatisierung von Abl\u00e4ufen mittels Skripts (insbesondere auch Pattern Matching und Regular Expressions,  Konfiguration, Wartbarkeit und Zuverl\u00e4ssigkeit von Skripts). Weiters Multithreading und ausgew\u00e4hlte Aspekte von paralleler sowie funktionaler Programmierung.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-web-analytics-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-web-analytics\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Web Engineering 5 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418505<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Web Analytics<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-web-analytics\"\n                                                        aria-labelledby=\"course-web-analytics-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        In der Lehrveranstaltung werden verschieden Methoden der Sammlung und Analyse von Webdaten behandelt. Das Seminar unterteilt sich in drei Abschnitte:  1) Statistische Analyse von Daten aus verf\u00fcgbaren Datenquellen wie die automatisch \u00fcber Server Logging und  User-Tracking erhobenen Datens\u00e4tze. 2) Analyse und Auswertung von dynamischen Datenquellen 3) Einsatz von intelligenten Algorithmen zur Datengewinnung wie Recommender Systeme\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"col-12\">\n                        <div class=\"accordion-element-accordion\">\n                            <a\n                                data-bs-toggle=\"collapse\"\n                                class=\"arrow-link large-arrow py-3 pe-1 d-block border-bottom collapsed\"\n                                href=\"#accordion-104225881\"\n                            >\n                                <h4 class=\"accordion-title mb-0 d-flex align-items-center justify-content-between\">\n                                    <span>6. Semester<\/span>\n                                    <svg width=\"12\" height=\"24\" viewBox=\"0 0 9 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path id=\"accordion_chevron\" d=\"M1.5 1.5L7.5 7.5L1.5 13.5\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\"\/>\n<\/svg>                                <\/h4>\n                            <\/a>\n                            <div\n                                class=\"collapse content-wrapper mt-3\"\n                                id=\"accordion-104225881\"\n                            >\n                                                                                                                                                                                                                                        <button\n                                                id=\"course-bachelorprufung-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-bachelorprufung\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Bachelorpr\u00fcfung |\n                                                            Modul-\/Abschlusspr\u00fcfung\n                                                            (FA)\n                                                            | Coursecode:\n                                                            220418608<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Bachelorpr\u00fcfung<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">0.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-bachelorprufung\"\n                                                        aria-labelledby=\"course-bachelorprufung-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        \n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-model-driven-development-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-model-driven-development\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Software Engineering 6 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418604<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Model-Driven Development<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-model-driven-development\"\n                                                        aria-labelledby=\"course-model-driven-development-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Einf\u00fchrung in die Automatisierung der Software Entwicklung durch Model-Driven Development: (i) Generic Libraries; (ii) Metamodeling (Metamodel Hierarchy, Model Validation, Domain Specific Languages); (iii) Generator Techniques; (iv) Integration of Generated Code.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-practical-software-engineering-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-practical-software-engineering\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Software Engineering 6 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418606<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Practical Software Engineering<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">7.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-practical-software-engineering\"\n                                                        aria-labelledby=\"course-practical-software-engineering-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Entwicklung einer open source Web Application unter praxisnahen Bedingungen: Agile Entwicklungsmethoden (XP, Scrum), Verteilte Entwicklerteams, Continuous Integration,  Continous Delivery.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-systemnahe-programmierung-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-systemnahe-programmierung\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Software Engineering 6 |\n                                                            \u00dcbung\n                                                            (UE)\n                                                            | Coursecode:\n                                                            220418605<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Systemnahe Programmierung<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">5.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-systemnahe-programmierung\"\n                                                        aria-labelledby=\"course-systemnahe-programmierung-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Erstellung von systemnahem Libraries und Applikationen basierend auf dem UNIX\/Linux Operating System:     &#8211; Environment of a UNIX process,     &#8211; Process control and relationships,     &#8211; Signals,     &#8211; Interprocess communication,     &#8211; TCP sockets.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-internetokonomie-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-internetokonomie\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 5 |\n                                                            Vorlesung\n                                                            (VO)\n                                                            | Coursecode:\n                                                            220418609<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Internet\u00f6konomie<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-internetokonomie\"\n                                                        aria-labelledby=\"course-internetokonomie-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        In dieser Lehrveranstaltung wird den Studierenden der Unterschied zwischen old und new economy auf der makro-, der mikro\u00f6konomischen, der betriebswirtschaftlichen Ebene an Hand von neuen Technologien auseinandergesetzt; dabei werden traditionelle, digitale und hybride Gesch\u00e4ftsmodelle (Kapitaleinsatz, Zeitfaktor, Material- und Personalressourcen) hinsichtlich Kundenorientierung und Qualit\u00e4tsbewusstsein analysiert. Online Marketing hebt die Vielf\u00e4ltigkeit dieser Unternehmensphilosophie von heute hervor und verkn\u00fcpft die zur Verf\u00fcgung stehenden Marketingma\u00dfnahmen unter verschiedenen Gesichtspunkten miteinander. Ziel der LV ist es, ein allgemeines Verst\u00e4ndnis f\u00fcr das K\u00e4ufer- und Verk\u00e4uferverhalten und Anwendungssensibilt\u00e4t f\u00fcr Online-Marketing zu entwickeln.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-unternehmensgrundungen-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-unternehmensgrundungen\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 5 |\n                                                            Integrierte Lehrveranstaltung\n                                                            (IL)\n                                                            | Coursecode:\n                                                            220418607<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Unternehmensgr\u00fcndungen<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-unternehmensgrundungen\"\n                                                        aria-labelledby=\"course-unternehmensgrundungen-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Die Studierenden erlangen Kenntnisse \u00fcber die M\u00f6glichkeiten das erlernte Wissen f\u00fcr die Gr\u00fcndung eines eigenen Unternehmens anzuwenden und werden dabei sowohl organisatorische, finanzielle als auch Management Kompetenzen erlangen. Die Lehrveranstaltung wird laufend durch Wissenstr\u00e4ger aus dem Gr\u00fcndungs- und Gr\u00fcndungsfinanzierungsbereich (WIFI \/ SFG) Gr\u00fcndungs- und Gr\u00fcndungsfinanzierungsbereich unterst\u00fctzt. Im Rahmen der Lehrveranstaltung erarbeiten die Studierenden nach den aktuellen Richtlinien einen Businessplan.\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-arbeitsrecht-und-personalmanagement-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-arbeitsrecht-und-personalmanagement\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 6 |\n                                                            Vorlesung\n                                                            (VO)\n                                                            | Coursecode:\n                                                            220418602<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Arbeitsrecht und Personalmanagement<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-arbeitsrecht-und-personalmanagement\"\n                                                        aria-labelledby=\"course-arbeitsrecht-und-personalmanagement-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Arbeitsrecht: Grundz\u00fcge des Individualarbeitsrechts sowie des Kollektiven Arbeitsrechts (Arbeitsvertrag, Dienstzettel, Arbeitgeber, Arbeitnehmer, Art des Arbeitsverh\u00e4ltnisses, Beendigung des Arbeitsverh\u00e4ltnisses, Kollektive Rechtsquellen, Betriebliche Arbeitnehmervertr\u00e4ge; Personalmanagement: Personalmanagement: Grundlagen und Rahmenbedingungen eines zielorientierten Personalmanagements, Personalmarketing, Personalentwicklung; die Studierenden besch\u00e4ftigen sich mit dem Produktionsfaktor Arbeit, insbesondere mit Personalf\u00fchrung und Personalverwaltung (Personalbedarfsplanung, Personalbeschaffung, Personalentwicklung)\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-innovationsmanagement-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-innovationsmanagement\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 6 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418603<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Innovationsmanagement<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">2.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-innovationsmanagement\"\n                                                        aria-labelledby=\"course-innovationsmanagement-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Notwendigkeit von Innovationen und Trends, Definition von Innovationsmanagement, Phasen des Innovationsmanagements, Innovationsmanagementmethoden, Aufbau von Innovationsteams, Einflussfaktoren des Innovationsmangements, Innovationsaudit, Implementierung von Innovationsprojekten\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                    <button\n                                                id=\"course-public-speaking-skills-trigger\"\n                                                type=\"button\"\n                                                class=\"course-item major-text-color-hover major-border-color-hover\"\n                                                x-data=\"{ isOpen: false }\"\n                                                x-on:click=\"isOpen = ! isOpen\"\n                                                :aria-expanded=\"isOpen\"\n                                                aria-controls=\"course-public-speaking-skills\"\n                                            >\n                                                <div class=\"p-3\">\n                                                    <div\n                                                        class=\"course-item__header\"\n                                                        data-specialisation_id=\n                                                    >\n                                                        <span>Wirtschaft und Recht 6 |\n                                                            Seminar\n                                                            (SE)\n                                                            | Coursecode:\n                                                            220418601<\/span>\n                                                    <\/div>\n                                                                                                            <small class=\"text-dark\">Unterrichtssprache\n                                                            Deutsch<\/small>\n                                                                                                        <div class=\"course-item__content\">\n                                                        <h5>Public Speaking Skills<\/h5>\n                                                        <div class=\"infos\">\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">3.00<\/h5>\n                                                                <span>ECTS<\/span>\n                                                            <\/div>\n                                                            <div>\n                                                                <h5 class=\"fs-4 fw-bold\">1.00<\/h5>\n                                                                <span>SWS<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                    <\/div>\n\n                                                    <div\n                                                        id=\"course-public-speaking-skills\"\n                                                        aria-labelledby=\"course-public-speaking-skills-trigger\"\n                                                        role=\"region\"\n                                                        :class=\"isOpen ? 'open' : ''\"\n                                                        class=\"course-item__description\"\n                                                    >\n                                                        Planung, Aufbau (Strukturierung) und Durchf\u00fchrung von Pr\u00e4sentationen; Erarbeitung und Anwendung verschiedener Pr\u00e4sentationstechniken unter Einbeziehung der sprachlichen und au\u00dfersprachlichen Mermale von Pr\u00e4sentationen (K\u00f6rpersprache, Rhetorik, Kommunikationsstrategien); effektiver Einsatz von Medien (Powerpoint, Flipchart, etc.).\n                                                    <\/div>\n\n                                                <\/div>\n                                            <\/button>\n                                                                                                                                        <\/div>\n                        <\/div>\n                    <\/div>\n                            \n                    <\/div>\n    <\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Um die vielseitige und praxisbezogene Ausbildung bestm\u00f6glich abzubilden, sind alle Inhalte des Studiums in themenbezogene Module zusammengefasst. Eine \u00dcbersicht aller Module mit zugeh\u00f6rigen Lehrveranstaltungen finden Sie hier.<\/p>\n","protected":false},"author":12,"featured_media":0,"parent":10000274,"menu_order":33,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.fh-joanneum.at\/software-design-and-cloud-computing\/berufsbegleitend\/wp-json\/wp\/v2\/pages\/10000295"}],"collection":[{"href":"https:\/\/www.fh-joanneum.at\/software-design-and-cloud-computing\/berufsbegleitend\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fh-joanneum.at\/software-design-and-cloud-computing\/berufsbegleitend\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/software-design-and-cloud-computing\/berufsbegleitend\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/software-design-and-cloud-computing\/berufsbegleitend\/wp-json\/wp\/v2\/comments?post=10000295"}],"version-history":[{"count":0,"href":"https:\/\/www.fh-joanneum.at\/software-design-and-cloud-computing\/berufsbegleitend\/wp-json\/wp\/v2\/pages\/10000295\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.fh-joanneum.at\/software-design-and-cloud-computing\/berufsbegleitend\/wp-json\/wp\/v2\/pages\/10000274"}],"wp:attachment":[{"href":"https:\/\/www.fh-joanneum.at\/software-design-and-cloud-computing\/berufsbegleitend\/wp-json\/wp\/v2\/media?parent=10000295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}